{"id":141355,"date":"2017-04-26T11:24:12","date_gmt":"2017-04-26T09:24:12","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=141355"},"modified":"2017-04-26T11:24:12","modified_gmt":"2017-04-26T09:24:12","slug":"denunciata-dal-personale-del-commissariato-di-siniscola-una-persona-per-furto","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2017\/04\/26\/denunciata-dal-personale-del-commissariato-di-siniscola-una-persona-per-furto\/","title":{"rendered":"Denunciata dal personale del commissariato di Siniscola una persona per furto"},"content":{"rendered":"<p>Nuoro, 26 Apr 2017 - Gli agenti del Commissariato di Siniscola hanno identificato e deferito alla Autorit\u00e0 Giudiziaria l\u2019autore di un furto compiuto all\u2019interno di una abitazione di Posada tra il 14 e il 18 Aprile scorso.<\/p>\n<p>La denunciante, una mamma di 43 anni, aveva deciso con la sua famiglia di trascorrere le festivit\u00e0 pasquali presso i genitori a Bitti ma nel rientrare nella sua abitazione, al rientro, ha trovato vuoti i cassetti dell\u2019armadio dove custodiva i gioielli, pertanto si \u00e8 subito recata presso il locale Commissariato per sporgere la denuncia.<\/p>\n<p>Gli agenti della Polizia si sono attivati immediatamente per cercare di ricostruire la dinamica del furto, battendo il territorio palmo a palmo, visionando le immagini delle telecamere e sentendo le testimonianze di alcuni abitanti del posto.<\/p>\n<p>L\u2019attivit\u00e0 svolta ha consentito in seguito il ritrovamento di due cellulari rubati proprio dall\u2019appartamento e l\u2019identificazione del probabile autore del furto che \u00e8 stato poi incastrato definitivamente una volta che gli agenti hanno scandagliato i vari compro oro della zona, nei quali in due giorni F.G.M., pregiudicato di 43 anni, aveva versato gli oggetti d\u2019oro rubati, i quali sono stati recuperati e restituiti al legittimo proprietario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuoro, 26 Apr 2017 &#8211; Gli agenti del Commissariato di Siniscola hanno identificato e deferito alla Autorit\u00e0 Giudiziaria l\u2019autore di un furto compiuto all\u2019interno di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":140632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/141355"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=141355"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/141355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/140632"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=141355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=141355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=141355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}