{"id":134460,"date":"2016-11-01T12:09:50","date_gmt":"2016-11-01T11:09:50","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=134460"},"modified":"2016-11-01T12:09:50","modified_gmt":"2016-11-01T11:09:50","slug":"nella-notte-di-halloween-3-persone-denunciate-dai-compagnia-carabinieri-di-siniscola","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2016\/11\/01\/nella-notte-di-halloween-3-persone-denunciate-dai-compagnia-carabinieri-di-siniscola\/","title":{"rendered":"Nella notte di halloween, 3 persone denunciate dai Compagnia carabinieri di Siniscola"},"content":{"rendered":"<p>Siniscola (Nu), 1 Nov 2016 - Durante un controllo straordinario del territorio, organizzato in occasione della Festa Di Halloween, i Carabinieri della Compagnia di Siniscola hanno denunciato 3 persone resesi responsabili di vari reati e segnalato alla Prefettura di Nuoro 2 ragazzi.<\/p>\n<p>In particolare, il controllo alla circolazione stradale, effettuato dalle pattuglie dell\u2019Arma sulle maggiori vie di comunicazione del territorio, ha portato al deferimento in stato di libert\u00e0 di 2 persone: tutti sono risultati positivi al test alcolemico notevolmente al di sopra del limite consentito dalla legge e per loro \u00e8 scattato immediatamente il ritiro della patente di guida.<\/p>\n<p>Un\u2019altra pattuglia dell\u2019Arma di Dorgali, sempre nella notte di oggi, ha denunciato una donna, che a seguito di una perquisizione domiciliare \u00e8 stata trovata in possesso di 11 grammi di marijuana, oltre a diverse infiorescenze e alcuni semi della stessa sostanza.<\/p>\n<p>Infine, 2 ragazzi di 17 e 25 anni sono stati perquisiti e trovati con indosso modiche quantit\u00e0 di marijuana per uso personale e per tale ragione, sono stati segnalati all\u2019autorit\u00e0 amministrativa quali assuntori di sostanze stupefacenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siniscola (Nu), 1 Nov 2016 &#8211; Durante un controllo straordinario del territorio, organizzato in occasione della Festa Di Halloween, i Carabinieri della Compagnia di Siniscola&#8230;<\/p>\n","protected":false},"author":2,"featured_media":22335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/134460"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=134460"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/134460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=134460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=134460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=134460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}