{"id":131059,"date":"2016-08-17T18:04:32","date_gmt":"2016-08-17T16:04:32","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=131059"},"modified":"2016-08-17T18:04:32","modified_gmt":"2016-08-17T16:04:32","slug":"ryanair-pigliaru-risposta-che-aspettavamo-merito-dellincessante-lavoro-della-regione-e-del-governo","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2016\/08\/17\/ryanair-pigliaru-risposta-che-aspettavamo-merito-dellincessante-lavoro-della-regione-e-del-governo\/","title":{"rendered":"Ryanair, Pigliaru: risposta che aspettavamo, merito dell&#8217;incessante lavoro della regione e del governo"},"content":{"rendered":"<p>Cagliari, 17 Ago 2016 -\u00a0\"\u00c8 il risultato che ci aspettavamo. Abbiamo creato le condizioni per il ritorno di Ryanair ad Alghero con l'avvio della privatizzazione dello scalo e la risposta \u00e8 arrivata. L'impegno preso di riaprire la base a fine novembre \u00e8 il frutto dell'incessante e costante lavoro portato avanti in questi mesi dalla Regione e dal Governo, in particolare dal ministro Del Rio, con l'obiettivo di salvare e rilanciare lo scalo del nord ovest dell'isola. Si va verso la soluzione: continuiamo a lavorare in questa direzione, la strategia \u00e8 quella giusta\". Lo dice il presidente della Regione, Francesco Pigliaru, dopo le dichiarazioni del Ceo Michael O'Leary a margine di una conferenza stampa al Ministero dei Trasporti sul nuovo piano industriale della compagnia aerea irlandese.<\/p>\n<p>\"Ryanair ha risposto positivamente alla nostra proposta di attendere la conclusione della privatizzazione obbligatoria del \"Riviera del Corallo\", comprendendo il momento cruciale e complesso che stiamo attraversando. Ora diventa fondamentale l'approvazione in tempi certi da parte del Consiglio Regionale della ricapitalizzazione dello scalo. La fase della privatizzazione - conclude il presidente Pigliaru - sar\u00e0 aperta all'apporto di qualsiasi investitore privato potenzialmente interessato\".<\/p>\n<p>\"Siamo certi - aggiunge l'assessore dei Trasporti Massimo Deiana - che una volta messa in sicurezza la societ\u00e0 di gestione dell'aeroporto Sogeaal, si potranno mettere in campo tutte le azioni per rilanciare il traffico internazionale e si apriranno nuove e importanti prospettive di sviluppo per l'economia di tutta la Sardegna\".<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 17 Ago 2016 &#8211;\u00a0&#8220;\u00c8 il risultato che ci aspettavamo. Abbiamo creato le condizioni per il ritorno di Ryanair ad Alghero con l&#8217;avvio della privatizzazione&#8230;<\/p>\n","protected":false},"author":2,"featured_media":123266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/131059"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=131059"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/131059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media\/123266"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=131059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=131059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=131059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}