{"id":130629,"date":"2016-08-05T16:07:49","date_gmt":"2016-08-05T14:07:49","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=130629"},"modified":"2016-08-05T16:07:49","modified_gmt":"2016-08-05T14:07:49","slug":"cooperazione-italia-francia-125-milioni-dalleuropa-alla-sardegna-con-il-primo-bando-paci-altro-tassello-per-superare-limiti-e-disagi-dellinsularita","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2016\/08\/05\/cooperazione-italia-francia-125-milioni-dalleuropa-alla-sardegna-con-il-primo-bando-paci-altro-tassello-per-superare-limiti-e-disagi-dellinsularita\/","title":{"rendered":"Cooperazione Italia-Francia, 12,5 milioni dall&#8217;Europa alla Sardegna con il primo bando. Paci: altro tassello per superare limiti e disagi dell&#8217;insularit\u00e0"},"content":{"rendered":"<p>Cagliari, 5 Ago 2016 -\u00a0Trentasei progetti finanziati in Sardegna con 12 milioni e mezzo di euro nel primo bando da 70 milioni (su un totale di 200) del Programma di Cooperazione Italia-Francia Marittimo 2014-2020 per progetti di Blue e Green economy, mobilit\u00e0, accessibilit\u00e0, innovazione, nautica, cantieristica, tutela del territorio e del patrimonio culturale, prevenzione dei rischi. Obiettivo delle Regioni coinvolte (Corsica, Sardegna, Liguria e le 5 province costiere delle Toscana, in pi\u00f9 i dipartimenti francesi delle Alpi-Marittime e del Var, situati in Provence-Alpes-C\u00f4te d'Azur), alle quali si chiede di elaborare progetti di interesse comune alle aree di cooperazione, \u00e8 quello di creare quello sviluppo intelligente, inclusivo e sostenibile che l'Unione Europea si \u00e8 prefissata di raggiungere entro i prossimi 4 anni. La strategia prevede di rafforzare la cooperazione transfrontaliera tra Italia e Francia per trasformare l\u2019area del Mediterraneo centro-settentrionale in una zona competitiva, sostenibile e inclusiva\u00a0che interessa 6 milioni e mezzo di cittadini. Il Po Marittimo era stato presentato ufficialmente a Pisa a luglio dell'anno scorso: sui 38 programmi complessivamente approvati, la Sardegna partecipa a 36 e in 7 \u00e8 capofila. Dei 71.539.907 euro assegnati, 60.763.173 provengono dal Fesr.<\/p>\n<p>\"Sono alcuni dei temi al centro del nostro programma di governo, superare i limiti dell'insularit\u00e0 e garantire infrastrutture, connessione, network - dice il vicepresidente della Regione Raffaele Paci -. Con questi programmi costruiamo ponti con le regioni che ci stanno pi\u00f9 vicine pur essendo distanti, facendo asse con Toscana e Liguria ma soprattutto con la Corsica che come noi \u00e8 fortemente penalizzata dal non avere ancora metano, dagli spostamenti possibili solo in nave e aereo, dalla mancanza di infrastrutture. Essere un'isola, per di pi\u00f9 periferica e scarsamente popolata, nel mondo di\u00a0oggi\u00a0genera un gap: dobbiamo riuscire a superarlo in fretta, anche attraverso il Progetto transfrontaliero che mette ancora molti soldi a disposizione. Con questa prima fase ci assicuriamo 12 milioni e mezzo di euro dimostrando cos\u00ec di essere capaci di elaborare rapidamente progetti validi e competitivi, di creare contatti e fare connessione. Per la prima volta ci sono anche i privati che sono fondamentali e vanno inseriti in ogni programma europeo\", conclude Paci.<\/p>\n<p>Il Programma si rivolge a un sistema vasto e articolato di potenziali beneficiari, per esempio centri di ricerca, Universit\u00e0, associazioni, sindacati, enti pubblici, piccole e medie imprese, aziende di trasporto, Autorit\u00e0 Portuali, servizi per l\u2019impiego, organismi di formazione. Quattro gli assi prioritari: Promozione della competitivit\u00e0 delle imprese nelle filiere transfrontaliere; Protezione e valorizzazione delle risorse naturali e culturali e gestione dei rischi; Miglioramento della connessione dei territori e della sostenibilit\u00e0 delle attivit\u00e0 portuali; Aumento delle opportunit\u00e0 di lavoro sostenibile e di qualit\u00e0 e di inserimento attraverso l\u2019attivit\u00e0 economica. Fra i progetti ammessi a finanziamento (in allegato l'elenco completo), si possono ricordare \"Proterina\", oltre 6 milioni di euro per migliorare la capacit\u00e0 delle istituzioni di prevenire il rischio alluvioni, puntando sul potenziamento della prevenzione, col rafforzamento dei sistemi di monitoraggio; \u00a0\"Girepam\", 5 milioni e 600mila euro per l'elaborazione di una strategia di gestione integrata delle reti ecologiche marino-costiere ideata e attuata dalle Regioni in rete con Parchi e Aree marine protette; \"ISOS\", 1 milione e mezzo per creare una rete di isole francesi e italiane impegnate nella preservazione dei patrimoni naturali e culturali insulari che sar\u00e0 animata attraverso vari eventi, con investimenti per la certificazione di isole sostenibili; \"Geecctt\", quasi 2 milioni per la gestione comune dei servizi transfrontalieri di trasporto tra le isole; \"Sedriport\", 1 milione e 800mila euro per risolvere il problema dell'insabbiamento dei porti dell'area transfrontaliera e individuare soluzioni per il ripristino dei fondali.<\/p>\n<p>Per ottobre \u00e8 previsto il secondo bando del programma, con un finanziamento di circa 70 milioni. Potranno essere presentate candidature su tutti i quattro Assi del Programma sui temi del turismo, della cultura, della sostenibilit\u00e0 dei porti, dell'info-mobilit\u00e0 e della formazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 5 Ago 2016 &#8211;\u00a0Trentasei progetti finanziati in Sardegna con 12 milioni e mezzo di euro nel primo bando da 70 milioni (su un totale&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/130629"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=130629"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/130629\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=130629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=130629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=130629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}