{"id":122149,"date":"2016-01-27T11:09:20","date_gmt":"2016-01-27T10:09:20","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=122149"},"modified":"2016-01-27T11:09:20","modified_gmt":"2016-01-27T10:09:20","slug":"universita-cagliari-hacker-criminalita-sul-web-e-dintorni","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2016\/01\/27\/universita-cagliari-hacker-criminalita-sul-web-e-dintorni\/","title":{"rendered":"Universit\u00e0 Cagliari &#8211; Hacker, criminalit\u00e0 sul web e dintorni"},"content":{"rendered":"<p>Cagliari, 27 Gen 2016 - Venerd\u00ec 29 gennaio, dalle 9 alle 17, l\u2019auditorium di Tiscali -\u00a0 S.S. 195 km 2, 300 - ospita l\u2019evento pubblico conclusivo del progetto europeo ILLBuster (Buster of ILLegal contents spread by malicious computer networks). Il progetto - coordinato dagli specialisti dell\u2019Universit\u00e0 di Cagliari \u2013 \u00e8 finanziato dalla Commissione Europea (Dg-Home) e ha sviluppato un sistema integrato per la rilevazione e classificazione semi-automatica delle attivit\u00e0 illegali in rete.<\/p>\n<p>Con \u201cThe ILLBuster Project Experience\u201d, interventi di Fabio Roli e Giuseppe Vaciago, si aprono i lavori. Il professor Roli (ordinario Sistemi elaborazione dell'informazione - Diee, dipartimento Ingegneria elettrica ed elettronica, Universit\u00e0 di Cagliari) \u00e8 il direttore del PRA Lab e presenta \u201cProject achievements and lessons learned\u201d. La scaletta vede relazioni di Aldona Trela (Europol EC3), Roberto Baldoni (direttore laboratorio nazionale Cyber Security), Raj Samani (Intel Security), Marco Morana (Svp Citigroup). Ai lavori - con al centro la cyber intelligence, un tema, visti i recenti fatti di terrorismo, molto seguito dall\u2019opinione pubblica - sono attesi anche esponenti delle forze dell\u2019ordine e di aziende operanti nei settori bancari, industriali, della finanza e della cyber security. Per partecipare \u00e8 richiesta l\u2019iscrizione con il modulo ad hoc reperibile su <a href=\"http:\/\/www.illbuster-project.eu\/index.php\/events\/final-event\">http:\/\/www.illbuster-project.eu\/index.php\/events\/final-event<\/a><\/p>\n<p>Tra gli specialisti del Diee - autori tra l\u2019altro del progetto CyberRoad e docenti nella Scuola di sicurezza informatica - coinvolti nell\u2019evento e nelle attivit\u00e0 del dipartimento, Giorgio Giacinto, Davide Ariu, Battista Biggio e Igino Corona. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 27 Gen 2016 &#8211; Venerd\u00ec 29 gennaio, dalle 9 alle 17, l\u2019auditorium di Tiscali &#8211;\u00a0 S.S. 195 km 2, 300 &#8211; ospita l\u2019evento pubblico&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/122149"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=122149"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/122149\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=122149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=122149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=122149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}