{"id":117812,"date":"2015-10-12T15:11:42","date_gmt":"2015-10-12T13:11:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=117812"},"modified":"2015-10-12T15:11:42","modified_gmt":"2015-10-12T13:11:42","slug":"mercoledi-14-ottobre-a-cagliari-la-presentazione-della-sesta-edizione-del-festival-nues-alle-ore-11-presso-il-serch-sottopiano-del-palazzo-civico-largo-carlo-felice-2","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/10\/12\/mercoledi-14-ottobre-a-cagliari-la-presentazione-della-sesta-edizione-del-festival-nues-alle-ore-11-presso-il-serch-sottopiano-del-palazzo-civico-largo-carlo-felice-2\/","title":{"rendered":"Mercoled\u00ec 14 ottobre a Cagliari la presentazione\u00a0della sesta edizione del festival Nues alle ore 11 presso il Serch, Sottopiano del Palazzo Civico &#8211; largo Carlo Felice, 2)"},"content":{"rendered":"<p>Cagliari, 12 Ott 2015 - Mercoled\u00ec 14 ottobre\u00a0a\u00a0Cagliari\u00a0al\u00a0SEARCH\u00a0- Sede Espositiva Archivio Storico Comunale, nel Sottopiano del Palazzo Civico (in\u00a0largo Carlo Felice, 2) si terr\u00e0 la presentazione alla stampa della\u00a0sesta edizione\u00a0di\u00a0Nues, il festival sui fumetti e i cartoni del Mediterraneo\u00a0promosso dal Centro Internazionale del Fumetto\u00a0con la direzione artistica di\u00a0Bepi Vigna\u00a0.<br \/>\nIn arrivo, tra il\u00a015 ottobre\u00a0e il\u00a03 dicembre\u00a0a\u00a0Cagliari\u00a0(ma con incursioni anche a\u00a0Iglesias,\u00a0Carbonia\u00a0e\u00a0Sassari),\u00a0presentazioni e\u00a0reading\u00a0letterari, mostre, conferenze e spettacoli, finestre aperte su novit\u00e0 editoriali di fumetti e\u00a0graphic novel\u00a0con autori e illustratori della scena italiana, siriana, tunisina e del Madagascar: un ricco cartellone racchiuso nel sottotitolo\u00a0\"Nuvole dal fronte\",\u00a0per esplorare i diversi risvolti della guerra e delle situazioni di conflittualit\u00e0 tra uomini,\u00a0leitmotiv\u00a0di questa edizione di Nues.<\/p>\n<p>Nel corso dell'incontro con i giornalisti, che avr\u00e0 inizio\u00a0alle 11, il direttore artistico\u00a0Bepi Vigna\u00a0illustrer\u00e0 il programma alla presenza dell'illustratrice tunisina\u00a0Takoua Ben Mohamed, protagonista,\u00a0l'indomani\u00a0(gioved\u00ec 15 ottobre) a\u00a0Cagliari, all'ExArt\u00a0(l'ex Liceo Artistico, in piazza Dettori 9) dell'appuntamento inaugurale del festival: il taglio del nastro\u00a0alle 18\u00a0della mostra\u00a0\"<a href=\"https:\/\/www.facebook.com\/IlFumettoInterculturaTakouaBenMohamed?fref=ts\">Woman Story, il Fumetto intercultura<\/a>\".<\/p>\n<p>Il progetto di\u00a0graphic journalism\u00a0della giovane artista (24 anni, nata a Douz, vive a Roma dall'et\u00e0 di 8 anni), gi\u00e0 presentato alla Camera dei Deputati, al TEDx di Matera, al Festival Internazionale del Giornalismo di Perugia, in varie universit\u00e0 italiane e in Argentina, far\u00e0 tappa in Sardegna grazie alla collaborazione tra il Centro Internazionale del Fumetto, lo\u00a0SPRAR\u00a0(Sistema di Protezione per Richiedenti Asilo e Rifugiati)\u00a0progetto \"Emilio Lussu\", la\u00a0Provincia di Cagliari, la\u00a0Comunit\u00e0 La Collina, l'associazione\u00a0Efys Onlus,\u00a0Typos Studio Editoriale. Nel corso della serata sar\u00e0 presentato il libro - catalogo della mostra (che rimarr\u00e0 aperta fino al 24 ottobre) dal titolo\u00a0\"Woman Story\"\u00a0(edizioni Taphros). Il volume, a cura di\u00a0Bepi Vigna\u00a0e con prefazione di\u00a0Don Ettore Cannavera, rappresenta la prima pubblicazione monografica del lavoro della disegnatrice.<\/p>\n<p>La sesta edizione di Nues \u00e8 organizzata con il contributo della Regione Autonoma della Sardegna, (Assessorato della Pubblica Istruzione, Beni Culturali, Informazione, Spettacolo e Sport), del Comune di Cagliari (Assessorato alla Cultura) e in collaborazione con Fondazione Sardegna Film Commission, SPRAR - Sistema di Protezione per Richiedenti Asilo e Rifugiati - Ministero dell'Interno, Provincia di Cagliari, MeM - Mediateca del Mediterraneo, L\u00ecberos - Festival letterario diffuso \u00c9ntula, Fondazione Giuseppe Dess\u00ec, Comunit\u00e0 La Collina, Sustainable Happiness, Miele Amaro - Il circolo dei lettori, Marina Caf\u00e8 Noir - Festival di letterature applicate, Hostel Marina Cagliari, GioCoMix, Associazione Efys onlus, Scuola Superiore Interpreti e Traduttori Verbum, Figli D'Arte Medas, Sukka, Is Mascareddas, Donna Ceteris, Corso di laurea in Scienze della comunicazione e Master in Management dei prodotti e servizi della comunicazione, Facolt\u00e0 Studi Umanistici di Cagliari, centro iniziative culturali Arci - Iglesias, Un indovino ci disse - il film, Conservatorio di Musica Giovanni Pierluigi da Palestrina - Cagliari, Typos studio editoriale, La Tarantola - centro di documentazione e studi sulle donne, editrice Taphros, Societ\u00e0 Umanitaria Cineteca Sarda, centro servizi culturali - Cagliari, Cagliari Festival Scienza. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 12 Ott 2015 &#8211; Mercoled\u00ec 14 ottobre\u00a0a\u00a0Cagliari\u00a0al\u00a0SEARCH\u00a0&#8211; Sede Espositiva Archivio Storico Comunale, nel Sottopiano del Palazzo Civico (in\u00a0largo Carlo Felice, 2) si terr\u00e0 la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":117813,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,54],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117812"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=117812"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=117812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=117812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=117812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}