{"id":117753,"date":"2015-10-10T16:07:05","date_gmt":"2015-10-10T14:07:05","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=117753"},"modified":"2015-10-10T16:07:05","modified_gmt":"2015-10-10T14:07:05","slug":"117753","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/10\/10\/117753\/","title":{"rendered":"Esplosione Ankara, Erdogan: &#8221; attacco contro l&#8217;unit\u00e0 del paese&#8221;"},"content":{"rendered":"<p>Ankara (Turkia), 10 Ott 2015 - \"Condanniamo con forza questo\u00a0attacco che prende di mira l'unit\u00e0. Siamo contro ogni forma di\u00a0terrorismo\". E' in queste parole la reazione del presidente turco Recep Tayyip Erdogan dopo le\u00a0due esplosioni che ad Ankara hanno causato186 feriti\u00a0a una manifestazione per la pace contro l'escalation\u00a0del conflitto con il Pkk curdo. I leader curdi hanno dichiarato un\u00a0cessate il fuoco unilaterale nel conflitto con la Turchia nel\u00a0sud-est del Paese,\u00a0a meno che il Pkk non venga attaccato.<\/p>\n<p>La reazione del Paese invece \u00e8 quella di uno schock fortissimo.\u00a0A tre\u00a0settimane dalle cruciali elezioni politiche, le due esplosioni rappresentano secondo il ministero dell'Interno un \"attacco alla pace e\u00a0alla democrazia in Turchia\". \u00a0Indagini sono state avviate per\u00a0chiarire se sia trattato di un attentato kamikaze, come\u00a0suggerito da alcuni media e ipotizzato da Kemal Kilicdaroglu,\u00a0leader del principale partito di opposizione, il\u00a0socialdemocratico Chp. \u00a0I servizi\u00a0di sicurezza hanno sottolineato che non ci sono state\u00a0auto distrutte nella duplice esplosione e che l'ipotesi di\u00a0un kamikaze \u00e8 plausibile.<\/p>\n<p>Il premier turco Ahmet Davutoglu ha subito convocato una\u00a0riunione d'emergenza sulla sicurezza, mentre i principali leader\u00a0politici hanno interrotto la loro campagna elettorale per\u00a0recarsi sul luogo dell'attacco. La manifestazione per la pace \u00e8\u00a0stata annullata e gli organizzatori hanno chiesto ai\u00a0partecipanti e a quelli che stavano arrivando da altre citt\u00e0 di\u00a0tornare a casa nel timore di nuovi attentati. \"Stiamo assistendo a un enorme massacro. Una continuazione\u00a0di quelli di Diyarbakir e Suruc\", ha denunciato il leader del\u00a0partito filo-curdo Hdp, Selahattin Demirtas, riferendosi\u00a0all'attentato a un suo comizio a Diyarbakir alla vigilia del\u00a0voto di giugno, in cui morirono 2 persone, e a quello del 20\u00a0luglio a Suruc, con 33 attivisti diretti a Kobane uccisi da un\u00a0kamikaze dell'Isis.<\/p>\n<p>Dall'estero il presidente russo, Vladimir Putin, ha inviato un telegramma di condoglianze al presidente turco Erdogan, esprimendo le proprie \"pi\u00f9 sincere condoglianze alle famiglie e agli amici delle vittime\" e ribadendo la volont\u00e0 di Mosca a collaborare con la Turchia per il contrasto al terrorismo e ha espresso la speranza che i colpevoli di un crimine tanto cinico siano consegnati alla giustizia. Anche il ministro degli Esteri Paolo Gentiloni ha inviato un\u00a0messaggio di cordoglio\u00a0al suo collega turco, Feridun\u00a0Sinirlioglu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ankara (Turkia), 10 Ott 2015 &#8211; &#8220;Condanniamo con forza questo\u00a0attacco che prende di mira l&#8217;unit\u00e0. Siamo contro ogni forma di\u00a0terrorismo&#8221;. E&#8217; in queste parole la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":117737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117753"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=117753"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=117753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=117753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=117753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}