{"id":117721,"date":"2015-10-10T10:20:00","date_gmt":"2015-10-10T08:20:00","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=117721"},"modified":"2015-10-10T10:20:00","modified_gmt":"2015-10-10T08:20:00","slug":"dallerasmus-welcome-week-allerasmus-welcome-day-una-settimana-di-eventi-per-accogliere-gli-studenti-stranieri-alluniversita-di-sassari","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/10\/10\/dallerasmus-welcome-week-allerasmus-welcome-day-una-settimana-di-eventi-per-accogliere-gli-studenti-stranieri-alluniversita-di-sassari\/","title":{"rendered":"Dall&#8217;Erasmus Welcome Week all&#8217;Erasmus Welcome Day una settimana di eventi per accogliere gli studenti stranieri all&#8217;Universit\u00e0 di Sassari"},"content":{"rendered":"<p>Sassari, 10 Nov 2015 - Non uno, ma sette giorni: il Benvenuto Erasmus dell'Universit\u00e0 di Sassari si moltiplica in tanti eventi diversi, tutti finalizzati ad accogliere gli studenti stranieri che si accingono a studiare nell'Ateneo turritano e a favorire l'integrazione. Il culmine si raggiunger\u00e0 venerd\u00ec 9 ottobre in aula Magna alle 18.00 con la serata del benvenuto ufficiale.<\/p>\n<p>Gli eventi della settimana. L'associazione ESN \u2013 Erasmus Student Network, promotrice della manifestazione assieme all'Universit\u00e0 di Sassari e all'Ersu, ha inaugurato oggi la Welcome Week con il City Game, a met\u00e0 tra la caccia al tesoro e la visita guidata della citt\u00e0. Un gioco per rompere il ghiaccio, conoscere gli studenti stranieri e non che frequentano l'Ateneo, futuri compagni di viaggio nell'avventura Erasmus appena cominciata negli scenari caratteristici, tutti da scoprire, offerti dalla citt\u00e0 di Sassari. L'Erasmus Welcome Week prosegue domani, marted\u00ec 6 ottobre, con l'Italian Night. Mercoled\u00ec 7 ottobre, grazie alla collaborazione del CUS Sassari, \u00e8 in programma un pomeriggio all\u2019insegna dello sport nei moderni impianti di San Giovanni, dove gli studenti potranno sperimentare diverse discipline, come il tiro con l\u2019arco e la scherma. La settimana si concluder\u00e0 con un tandem linguistico e una gita con visita guidata al sito archeologico di Monte d\u2019Accoddi, dove la folta comitiva degli studenti Erasmus potr\u00e0 recarsi grazie al servizio offerto dall'Azienda Trasporti Pubblici (ATP) di Sassari.<\/p>\n<p>I numeri. Quest'anno sono circa 120 gli Erasmus in mobilit\u00e0 in entrata per fini di studio previsti per il primo semestre (+ 20% rispetto al 2014-15, quando furono 98). Ad essi si devono aggiungere 18 Erasmus incoming in mobilit\u00e0 per tirocini (erano 14 l'anno scorso) e i 30 studenti provenienti dalle universit\u00e0 del Maghreb di Tunisia, Algeria e Marocco, iscritti a diversi corsi di laurea dell'Ateneo nel quadro degli accordi promossi dall'Unione delle Universit\u00e0 del Mediterraneo (Unimed), in collaborazione con la Fondazione Banco di Sardegna.<\/p>\n<p>L'Erasmus Welcome Day. Venerd\u00ec 9 ottobre si terr\u00e0 il classico \"Erasmus Welcome Day\", il benvenuto istituzionale che l'Ateneo di Sassari rivolge tutti gli anni agli studenti stranieri in entrata. La cerimonia si svolger\u00e0 in Aula Magna a partire dalle 18.00. In apertura sono previsti gli interventi di saluto del Magnifico Rettore, Prof. Massimo Carpinelli, del Sindaco di Sassari, Dott. Nicola Sanna, del Prof. Piero Sanna e del Prof. Giuseppe Moniello, Delegati del Rettore per la mobilit\u00e0 internazionale studentesca e per l\u2019Erasmus, di Valentina Pintus e Mauro Pala, rispettivamente rappresentante locale e vice presidente dell\u2019Associazione ErasmuSS- ESN Sassari. Coordiner\u00e0 la serata la Presidente dell\u2019Erasmus Student Network (ESN) Sassari, Alessandra Sechi. La cerimonia sar\u00e0 animata dagli intermezzi musicali offerti dagli allievi del corso di Jazz del Conservatorio \"Luigi Canepa\", dai tenores del Coro di Abbasanta e dal duo \u201cChitarra Erasmus\u201d degli studenti spagnoli, Berto e Adri\u00e0. Saranno presenti i componenti del Comitato Erasmus d'Ateneo, la prof.ssa Elena Sanna Ticca, Garante degli studenti stranieri e le delegazioni accademiche dei tredici Dipartimenti, che al termine della serata, negli stand allestiti nel loggiato del Palazzo centrale, daranno il benvenuto ciascuna ai propri studenti incoming.<\/p>\n<p>L'Erasmus Welcome Day e l'Erasmus Welcome Week sono organizzati dall'associazione ESN-Erasmus Student Network sezione di Sassari, in collaborazione con il Comitato Erasmus di Ateneo e l'Ufficio Relazioni Internazionali, con il contributo dell'Ersu. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sassari, 10 Nov 2015 &#8211; Non uno, ma sette giorni: il Benvenuto Erasmus dell&#8217;Universit\u00e0 di Sassari si moltiplica in tanti eventi diversi, tutti finalizzati ad&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,53],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117721"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=117721"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117721\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=117721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=117721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=117721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}