{"id":117716,"date":"2015-10-10T09:36:53","date_gmt":"2015-10-10T07:36:53","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=117716"},"modified":"2015-10-10T09:36:53","modified_gmt":"2015-10-10T07:36:53","slug":"attivita-dei-carabinieri-della-compagnia-di-san-vito-giovane-di-villasimius-ricercato-per-il-reato-di-danneggiamento-aggravato-di-una-moto-e-arrestato-dai-carabinieri","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/10\/10\/attivita-dei-carabinieri-della-compagnia-di-san-vito-giovane-di-villasimius-ricercato-per-il-reato-di-danneggiamento-aggravato-di-una-moto-e-arrestato-dai-carabinieri\/","title":{"rendered":"Attivit\u00e0 dei carabinieri della compagnia di San Vito: Giovane di Villasimius ricercato per il reato di danneggiamento aggravato di una moto e arrestato dai carabinieri"},"content":{"rendered":"<p>San Vito (Ca), 10 Ott 2015 - In tutto il Sarrabus una serie di controlli serali e notturni ha consentito ai Carabinieri della Compagnia di San Vito, di rintracciare a Villasimius e arrestare C.M. un 35enne del luogo.<\/p>\n<p>L\u2019uomo che tempo addietro era stato denunciato dai militari di Villasimius per danneggiamento aggravato di una moto, da maggio scorso era destinatario di un ordine di esecuzione per la carcerazione in regime di detenzione domiciliare. Quindi \u00e8 stato rintracciato nel centro abitato e al termine degli accertamenti \u00e8 stato trasferito presso la propria abitazione in detenzione domiciliare.<\/p>\n<p>Inoltre, a San Vito, gli uomini dell\u2019Arma, hanno denunciato all\u2019Autorit\u00e0 Giudiziaria per porto di armi od oggetti atti ad offendere, C.S. di 53 anni, di Cagliari, perch\u00e9, a piedi nel centro abitato, \u00e8 stato trovato in possesso, senza giustificato motivo, di 18 coltelli che i militari hanno subito sequestrato.<\/p>\n<p>Nella notte i Carabinieri, che presidiavano le strade principali anche alla luce delle perdurante stato di allerta meteo, hanno controllate oltre 50 autovetture e pi\u00f9 di 60 persone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Vito (Ca), 10 Ott 2015 &#8211; In tutto il Sarrabus una serie di controlli serali e notturni ha consentito ai Carabinieri della Compagnia di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":74666,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,55],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117716"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=117716"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=117716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=117716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=117716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}