{"id":117708,"date":"2015-10-10T08:30:43","date_gmt":"2015-10-10T06:30:43","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=117708"},"modified":"2015-10-10T08:30:43","modified_gmt":"2015-10-10T06:30:43","slug":"117708","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/10\/10\/117708\/","title":{"rendered":"Maltempo \u2013 Allarme rosso in tutta la Sardegna dove torna la paura."},"content":{"rendered":"<p>Cagliari, 10 Ott 2015 - Si convive con la paura in Sardegna, col terrore che la natura, la pioggia e l'acqua possano tornare a devastare il territorio. L'incubo alluvione torna nuovamente nell'isola con l'allerta meteo con codice rosso lanciata dalla Protezione civile. La perturbazione nordafricana che ha raggiunto l'isola si sposter\u00e0 poi anche sulle regioni centro meridionali tirreniche. Il Dipartimento della Protezione Civile ha emesso un'allerta meteo, gli esperti prevedono precipitazioni diffuse, localmente anche molto intense e accompagnate da fulmini e forti raffiche di vento, prima su Campania e Lazio e successivamente su Abruzzo, Molise, Puglia, Basilicata e Calabria. Nella notte i temporali interesseranno anche Marche e Umbria mentre dalle prime ore di domani sono previsti anche venti forti su Marche, Umbria, Lazio, Abruzzo, Molise, Campania, Puglia, Basilicata e Calabria.<\/p>\n<p>Le criticit\u00e0 maggiori in Sardegna saranno a Montevecchio, Iglesiente, Campidano, Flumendosa-Flumineddu e Gallura. Il sindaco di Nuoro, Andrea Soddu ha disposto immediatamente la chiusura di tutte le scuole gi\u00e0 dal pomeriggio di ieri e per oggi e ordinato la chiusura della Galleria di Mughina, simbolo della tragica alluvione del 18 novembre 2013 quando venne completamente sommersa dall'acqua. Chiusura delle scuole disposta anche dal sindaco di Olbia, Gianni Giovannelli, dal sindaco di Cagliari, Massimo Zedda, da quello di Carbonia, Giuseppe Casti. A Cagliari sospese anche le attivit\u00e0 dell'Universit\u00e0. L'assessore regionale dell'Ambiente con delega alla Protezione civile, Donatella Spano, ha rinnovato l'appello alla popolazione di seguire le misure di precauzione e ai sindaci di attuare le procedure previste dal Manuale delle allerte e dai piani comunali di protezione civile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 10 Ott 2015 &#8211; Si convive con la paura in Sardegna, col terrore che la natura, la pioggia e l&#8217;acqua possano tornare a devastare&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117708"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=117708"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117708\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=117708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=117708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=117708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}