{"id":117536,"date":"2015-10-07T13:56:29","date_gmt":"2015-10-07T11:56:29","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=117536"},"modified":"2015-10-07T13:56:29","modified_gmt":"2015-10-07T11:56:29","slug":"artigianato-igp-per-filigrana-morandi-ulteriore-tassello-per-tutela-qualita-e-innovazione","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/10\/07\/artigianato-igp-per-filigrana-morandi-ulteriore-tassello-per-tutela-qualita-e-innovazione\/","title":{"rendered":"Artigianato: Igp per filigrana. Morandi: ulteriore tassello per tutela qualit\u00e0 e innovazione"},"content":{"rendered":"<p>Cagliari, 7 Ott 2015 -\u00a0Ci sono anche le filigrane della Sardegna tra le eccellenze artigiane per le quali l\u2019Europarlamento ha dato il via libera all\u2019estensione della tutela Igp.<br \/>\nProspettive commerciali.\u00a0Dopo il voto a stragrande maggioranza dell\u2019Assemblea di Strasburgo, toccher\u00e0 ora alla Commissione Europea dar seguito a un conseguente provvedimento. Pi\u00f9 di 800 prodotti artigianali europei potrebbero essere associati al marchio \"Indicazione geografica protetta\" favorendo l'apertura di interessanti prospettive commerciali per tante realt\u00e0 locali diffuse in Italia, e in particolare in Sardegna.<br \/>\nMaggiore tutela.\u00a0\u201cL\u2019estensione delle indicazioni geografiche alle eccellenze artigiane aumenterebbe la tutela della qualit\u00e0, valorizzando una delle produzioni maggiormente legata a cultura e identit\u00e0 isolane - commenta l\u2019assessore del Turismo, Artigianato e Commercio, Francesco Morandi -. La possibilit\u00e0 di chiederne il riconoscimento per le espressioni nelle varie categorie merceologiche, offrirebbe un'ulteriore opportunit\u00e0 da valutare con gli operatori\".<br \/>\nProgetto di rilancio.\u00a0\"Abbiamo elaborato un ambizioso\u00a0progetto di\u00a0rilancio dell\u2019artigianato artistico, tradizionale e di design all\u2019interno del quale il marchio \u2018Isola\u2019 rappresenter\u00e0 un valore aggiunto da rafforzare e condividere con i produttori. La capacit\u00e0 di investire, coniugare innovazione e tradizione e di intrecciare i valori identitari - conclude l\u2019esponente della Giunta Pigliaru - rappresentata dall\u2019artigianato associato al settore turistico, consente di ripensare il modo di stare sul mercato e di orientarsi su nuovi strumenti per l\u2019internazionalizzazione e l\u2019e-commerce\". Red<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 7 Ott 2015 &#8211;\u00a0Ci sono anche le filigrane della Sardegna tra le eccellenze artigiane per le quali l\u2019Europarlamento ha dato il via libera all\u2019estensione&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117536"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=117536"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117536\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=117536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=117536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=117536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}