{"id":117494,"date":"2015-10-07T08:24:34","date_gmt":"2015-10-07T06:24:34","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=117494"},"modified":"2015-10-07T08:24:34","modified_gmt":"2015-10-07T06:24:34","slug":"lavori-consiglio-sardegna-del-6-ottobre-2915-laula-approva-un-ordine-del-giorno-unitario-contro-la-chiusura-della-prefettura-di-oristano-2","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/10\/07\/lavori-consiglio-sardegna-del-6-ottobre-2915-laula-approva-un-ordine-del-giorno-unitario-contro-la-chiusura-della-prefettura-di-oristano-2\/","title":{"rendered":"Lavori Consiglio Sardegna del 6 Ottobre 2915: l\u2019Aula approva un ordine del giorno unitario contro la chiusura della Prefettura di Oristano (2)"},"content":{"rendered":"<p>Cagliari, 2915 - Il consigliere Marco Tedde (FI) ha riaffermato che il problema contingente \u00e8 rappresentato dalla soppressione della prefettura di Oristano ma che il vero tema \u00e8 per\u00f2 \u201cla desertificazione istituzionale della Sardegna\u201d. \u00abSiamo la vera e unica isola isolata \u2013 ha dichiarato il consigliere della minoranza - e viviamo un momento e una situazione terribile per quanto attiene i trasporti mentre lo Stato arretra con la cancellazione di motorizzazione, camere di commercio, prefetture etc.\u00bb.<\/p>\n<p>Tedde ha criticato inoltre i rappresentanti in Parlamento del territorio di Oristano che \u00abhanno votato la delega al governo per sopprimere le prefetture\u00bb. L\u2019esponente di Forza Italia ha parlato di un \u201catteggiamento remissivo nei confronti di Renzi\u201d da parte dei parlamentari del territorio e della Regione. A giudizio di Tedde, i servizi ai cittadini garantiti dagli uffici della prefettura di Oristano non potranno essere conservati ed ha sottolineato le caratteristica peculiari della Sardegna ad incominciare dal basso indice di densit\u00e0 demografica a fronte di un territorio assai vasto.<\/p>\n<p>\u00abLo Stato \u2013 ha insistito il consigliere di Fi - lo vediamo da lontano mentre come sardi ci paghiamo la Sanit\u00e0 e la Continuit\u00e0 territoriale ed \u00e8 anche per questa ragione affermo che Oristano non pu\u00f2 tollerare cancellazione di ulteriori servizi essenziali e vedere a rischio la sicurezza\u00bb. Tedde ha concluso con l\u2019auspicio di una forte presa di posizione unitaria del Consiglio regionale per contrastare l\u2019avanzata di un \u201cimpoverimento istituzionale che non riguarda solo Oristano ma l\u2019intera comunit\u00e0 sarda\u201d.<\/p>\n<p>Il consigliere Gianmario Tendas (Pd), ha ringraziato in apertura del suo intervento il presidente del Consiglio e la conferenza capigruppo per la tempestivit\u00e0 con la quale \u00e8 stato portato all\u2019attenzione dell\u2019Aula il tema della soppressione della prefettura di Oristano. Il consigliere della maggioranza ha sottolineato come la \u201cvertenza\u201d sia particolarmente avvertita nel territorio dell\u2019oristanese che unitariamente e con forza \u201cesprime forte contrariet\u00e0 per l\u2019arretramento dello Stato nel territorio\u201d. Tendas ha ricordato quindi i tagli programmati con la spending review ed ha affermato che tra i criteri utilizzati per individuare le prefetture da sopprimere deve essere tenuta in considerazione anche l\u2019estensione territoriale dell\u2019oristanese. \u00abUn conto \u2013 ha dichiarato Tendas - \u00e8 accorpare la prefettura di Chieti con Pescara che dista 20 chilometri, cos\u00ec come Prato da Pistoia, ma Oristano dista da Nuoro oltre novanta chilometri ed \u00e8 carente la viabilit\u00e0 e il servizio offerto dal trasporto pubblico \u00e8 disastroso\u00bb. Tendas ha quindi auspicato \u201cl\u2019apertura di un tavolo per scongiurare la soppressione della prefettura di Oristano\u201d.<\/p>\n<p>Il consigliere, Augusto Cherchi (Sovranit\u00e0, democrazia e lavoro) ha affermato che \u00e8 in corso ormai da tempo, un piano di dimagrimento della pubblica amministrazione, da parte dello Stato italiano ed ha citato, a titolo d\u2019esempio, la cancellazione delle province. \u00abUn intento nobile quello della razionalizzazione dei costi \u2013 ha detto il consigliere di maggioranza - ma che si sta traducendo in un nuovo tentativo accentratore da parte dello Stato, come dimostra l\u2019intervento inopportuno fatto con la soppressione della prefettura di Oristano\u00bb. Cherchi ha quindi ribadito la distanza tra Oristano e Nuoro per evidenziare il livello dei disagi cui andranno incontro i cittadini e i lavoratori ed ha insistito: \u00abSe si vuole abolire la prefettura, allora si aboliscano tutte\u00bb. Augusto Cherchi ha quindi citato il modello della regione Valle d\u2019Aosta (\u00abnon ha n\u00e9 prefetture e n\u00e9 province\u00bb) ed ha auspicato \u00abun ridisegno di funzioni e servizi per governare da noi il nostro territorio come dobbiamo fare su trasporti, sanit\u00e0 e scuola e riscossione tributi\u00bb.<\/p>\n<p>Il consigliere, Gianni Lampis (Misto-Fd\u2019I) ha espresso solidariet\u00e0 ai sindaci del\u2019oristanese perch\u00e9 \u2013 cos\u00ec ha detto - vedranno i loro uffici pieni di cittadini che lamentano ulteriori disagi e nuove penalizzazioni. \u00abE\u2019 facile \u2013 ha aggiunto - abolire la prefettura di Monza ma in Sardegna il ragionamento che vale in Lombardia non si pu\u00f2 fare per via dei trasporti e della viabilit\u00e0\u00bb. Il consigliere della minoranza ha quindi citato il caso di San Nicol\u00f2 d\u2019Arcidano: un cittadino che vi risiede per arrivare a Nuoro con i mezzi pubblici dovrebbe partire il giorno precedente\u00bb. Lampis ha definito i cittadini e i lavoratori della prefettura \u201cvittime di tagli fatti senza raziocinio\u201d. L\u2019esponente di Fratelli d\u2019Italia ha inoltre sottolineato le difficolt\u00e0 del Medio Campidano: \u00abE\u2019 una sorta di terra di mezzo che vede aumentare i reati e la fuga dello Stato allarga i confini della terra di mezzo aggregando oggi Oristano\u00bb.<\/p>\n<p>\u00abNon \u00e8 questo il futuro che vogliamo per la Sardegna \u2013 ha concluso Lampis - e oggi dobbiamo dare prova di unit\u00e0 per difendere la prefettura perch\u00e9 presidio dello Stato nell\u2019Isola\u00bb.<\/p>\n<p>Il consigliere Christian Solinas (Psd\u2019Az), ha ricordato la storica contrariet\u00e0 dei sardisti alla presenza delle prefetture nell\u2019Isola ed ha precisato: \u00abNon siamo per la desertificazione della presenza pubblica nell\u2019Isola ma vogliamo essere noi lo Stato in Sardegna\u00bb. \u00abC\u2019\u00e8 un rigurgito centralista che taglia le periferie e porta verso Roma servizi e funzioni\u00bb, ha proseguito il consigliere della minoranza, \u00abed \u00e8 questa una precisa idea di paese che questo governo sta portando avanti\u00bb. Christian Solinas ha quindi invitato la Regione a \u201cdare il buon esempio\u201d per non allontanare i servizi dai cittadini e censurando i tagli dello Stato. Il rappresentante del Psd\u2019Az ha sottolineato l\u2019esigenza di una rivisitazione della Regione (\u00abperch\u00e9 non portare gli enti agricoli a Oristano?\u00bb) e dimostrare che \u00abquest\u2019Aula davanti allo Stato ha un\u2019idea di presenza delle istituzioni e dei servizi che non penalizza e marginalizza nessuno\u00bb.<\/p>\n<p>Il capogruppo dei Riformatori, Attilio Dedoni ha rivolto apprezzamento per gli interventi dei consiglieri delle altre province, diverse da quelle di Oristano, \u00abperch\u00e9 dimostrano di aver colto il senso \u201cvero\u201d della discussione\u00bb. Il consigliere della minoranza ha quindi domandato \u201cQual \u00e8 la logica che ha spinto lo Stato a sopprimere la prefettura di Oristano?\u201d. Dedoni ha ricordato quindi l\u2019esigenza di garantire i servizi ai cittadini e le necessarie tutele per i lavoratori della prefettura. Il consigliere dei Riformatori ha insistito sulle difficolt\u00e0 nei collegamenti e sulla distanza che corre tra Oristano e Nuoro: \u00abL\u2019Italia non \u00e8 il Lombardo-Veneto e non pu\u00f2 essere quella la misura con cui si decidono i taglia in Sardegna\u00bb.\u00a0 Dedoni ha concluso con una critica: \u00abI rappresentanti del popolo sardo non sono stati all\u2019altezza per reggere un confronto alto e aspro con il governo e rivendicare tutto ci\u00f2 che il governo toglie alla Sardegna, ad incominciare dai presidi di cultura e civilt\u00e0\u00bb. Segue<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cagliari, 2915 &#8211; Il consigliere Marco Tedde (FI) ha riaffermato che il problema contingente \u00e8 rappresentato dalla soppressione della prefettura di Oristano ma che il&#8230;<\/p>\n","protected":false},"author":2,"featured_media":28992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,52],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117494"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=117494"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=117494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=117494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=117494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}