{"id":117355,"date":"2015-10-05T11:47:02","date_gmt":"2015-10-05T09:47:02","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=117355"},"modified":"2015-10-05T11:47:02","modified_gmt":"2015-10-05T09:47:02","slug":"calcio-serie-a-80","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/10\/05\/calcio-serie-a-80\/","title":{"rendered":"Calcio \u2013 Serie A"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Cagliari, 4 Ott 2015 - Fiorentina-Atalanta 3-0 Gara in discesa per i toscani che gi\u00e0 al 6' passano in\u00a0vantaggio su rigore, causato da Paletta per un intervento giudicato da rigore su Blaszczykowski. Il difensore italo-argentino viene anche espulso dall'arbitro Massa (5'). Dal dischetto va Josip Ilicic che trasforrma. Per l'attaccante sloveno \u00e8 il terzo centro stagionale, sempre su rigore. All'11' Borja Valero va vicino al raddoppio, ma colpisce il palo. Sulla ribattuta Badelj mette a lato. L'Atalanta, in inferiorit\u00e0 numerica, cerca di non arrendersi e sfiora il pari con Gomez e, soprattutto, con Moralez che a tu per tu con Tatarusanu colpisce il corpo del portierone rumeno. Ma al 34' la Fiorentina raddoppia e manda al tappeto i lombardi. Il colpo del ko arriva al termine di una bella azione: Bernardeschi serve Borja Valero all'interno dell'area, con lo spagnolo che, tutto solo, trafigge Sportiello. Il match, in pratica, si chiude qui.Da segnalare solo l'occasione capitata a Marcos Alonso e poco altro. I viola non infieriscono, i nerazzurri si difendono. Finisce 3-0 grazie al gol nel recupero del neoentrato Verd\u00f9 su un assist 'al bacio' di Kalinic. La squadra del tecnico portoghese Paulo Sousa si prende cos\u00ec il primato solitari in vetta alla classifica, per i bergamaschi un ko che non cancella affatto l'ottimo inizio di stagione.<\/p>\n<p>Milan-Napoli 4-0 Affonda il Milan a San Siro sotto i colpi di un ottimo Napoli. Gli uomini di Sarri sbloccano il risultato al 13' con la seconda rete stagionale di Allan. Il centrocampista brasiliano, ben servito da Insigne che approfitta di un errore di Zapata, stoppa di destro, entra in area e batte Diego Lopez. Partenopei in controllo, Milan in affanno. Gli uomini di Mihajlovic faticano a frenare la velocit\u00e0 e la verve degli attaccanti del Napoli, soprattutto quella di un Insigne a tratti imprendibile, mentre in avanti appaiono davvero impalpabili con il tandem Bacca-Luiz Adriano non pervenuto (Balotelli, infortunato, \u00e8 in tribuna). Il, logico, raddoppio dei campani arriva nel secondo tempo, al 48'. Bello lo scambio Insigne-Higuain-Insigne che infila il portiere rossonero sul secondo palo. Milan ko. C'\u00e8 il tempo per vedere la doppietta personale di Insigne (che aggancia a quota 5 il suo partner d'attacco Higuain nella classifica dei marcatori) al minuto numero 68 con una bella punizione e per la sfortunata autorete del difensore brasiliano Rodrigo Ely che beffa il connazionale Diego Lopez infilando nella sua porta (77'). E' il poker. Il Napoli sbanca il Meazza e prosegue la sua risalita in classifica agganciando Sassuolo e Chievo al sesto posto, a quota 12 punti. Un autentico crollo per il Milan e ora la panchina di Mihajlovic non appare pi\u00f9 tanto sicura<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Cagliari, 4 Ott 2015 &#8211; Fiorentina-Atalanta 3-0 Gara in discesa per i toscani che gi\u00e0 al 6&#8242; passano in\u00a0vantaggio su rigore, causato da Paletta&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,56],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117355"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=117355"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117355\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=117355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=117355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=117355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}