{"id":117304,"date":"2015-10-03T12:01:28","date_gmt":"2015-10-03T10:01:28","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/?p=117304"},"modified":"2015-10-03T12:01:28","modified_gmt":"2015-10-03T10:01:28","slug":"riforme-dopo-il-caos-per-il-gestaccio-di-barani-via-libera-a-emendamento-articolo-2","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/10\/03\/riforme-dopo-il-caos-per-il-gestaccio-di-barani-via-libera-a-emendamento-articolo-2\/","title":{"rendered":"Riforme: dopo il caos per il gestaccio di Barani, via libera a emendamento articolo 2."},"content":{"rendered":"<p>Roma, 3 Ott 2015 - Voto decisivo oggi a Palazzo Madama sulle riforme costituzionali.\u00a0Dopo le turbolenze di ieri con il caso del\u00a0gesto offensivo del senatore Barani, l'Aula ha dato il via libera all'emendamento Finocchiaro che modifica l'articolo 2 del ddl\u00a0riforme. I s\u00ec sono stati 169, i voti contrari 69 e 3 astenuti.<\/p>\n<p>L'emendamento Finocchiaro, che recepisce gli accordi interni al Pd e nella maggioranza, prevede che i consiglieri regionali e sindaci (componenti del nuovo Senato) siano scelti dai cittadini e poi ratificati dai Consigli regionali.<\/p>\n<p>\"Ieri \u00e8 stata una giornata difficile e per tutti noi mortificante ma anche sono anche state giornate in cui il Senato ha veramente discusso nel merito della riforma discutendo dell'articolo 2\", ha detto la prima firmataria dell'emendamento 'di mediazione' Finocchiaro. L'approvazione del testo\u00a0che conferma il Senato espressione degli enti\u00a0territoriali ma introduce il coinvolgimento degli elettori nella\u00a0scelta dei senatori, aggiunge, \"non \u00e8 una sconfitta di una parte\", cio\u00e8 di\u00a0quanti proponevano il Senato delle garanzie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 3 Ott 2015 &#8211; Voto decisivo oggi a Palazzo Madama sulle riforme costituzionali.\u00a0Dopo le turbolenze di ieri con il caso del\u00a0gesto offensivo del senatore&#8230;<\/p>\n","protected":false},"author":2,"featured_media":24520,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49,51],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117304"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=117304"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/117304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=117304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=117304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=117304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}