{"id":114885,"date":"2015-01-17T17:20:52","date_gmt":"2015-01-17T16:20:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/17\/01\/2015\/nel-territorio-del-comune-di-orani-ritrovamento-esplosivo-dal-personale-della-polizia-di-ottana"},"modified":"2015-01-17T17:20:52","modified_gmt":"2015-01-17T16:20:52","slug":"nel-territorio-del-comune-di-orani-ritrovamento-esplosivo-dal-personale-della-polizia-di-ottana","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/01\/17\/nel-territorio-del-comune-di-orani-ritrovamento-esplosivo-dal-personale-della-polizia-di-ottana\/","title":{"rendered":"Nel territorio del comune di Orani ritrovamento esplosivo dal personale della Polizia di Ottana."},"content":{"rendered":"<p>Ieri mattina, nei pressi della SS 537, in territorio del Comune di Orani, personale del Commissariato P.S. di Ottana e della Squadra Cinofili della Questura di Oristano, hanno trovato un sacchetto di plastica con all\u2019interno del materiale esplodente.<\/p>\n<p>Il plico, composto da 2 candelotti rispettivamente di gelatina esplosiva di gr.600 e di Tutagex di 400 grammi, era avvolto nella carta stagnola.<br \/>Nel sacchetto vi erano, sempre avvolti nella carta stagnola, anche una miccia e un detonatore.<\/p>\n<p>Sul posto \u00e8 intervenuto personale della Questura di Nuoro della Polizia Scientifica e del Nucleo Artificieri dei Carabinieri che hanno poi messo in sicurezza il materiale.<\/p>\n<p>L\u2019Autorit\u00e0 Giudiziaria ha disposto la distruzione di quanto rinvenuto.<\/p>\n<p>Indagini a cura del Commissariato P.S di Ottana.<\/p>\n<p><b style=\"mso-bidi-font-weight: normal;\"><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ieri mattina, nei pressi della SS 537, in territorio del Comune di Orani, personale del Commissariato P.S. di Ottana e della Squadra Cinofili della Questura&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114885"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=114885"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114885\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=114885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=114885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=114885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}