{"id":114857,"date":"2015-01-20T17:20:52","date_gmt":"2015-01-20T16:20:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/20\/01\/2015\/arrestati-dal-personale-della-polizia-di-stato-due-pluripregiudicati-per-furto-in-concorso-ed-anche-denunciato-masala-anche-in-stato-di-liberta-per-ricettazione"},"modified":"2015-01-20T17:20:52","modified_gmt":"2015-01-20T16:20:52","slug":"arrestati-dal-personale-della-polizia-di-stato-due-pluripregiudicati-per-furto-in-concorso-ed-anche-denunciato-masala-anche-in-stato-di-liberta-per-ricettazione","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/01\/20\/arrestati-dal-personale-della-polizia-di-stato-due-pluripregiudicati-per-furto-in-concorso-ed-anche-denunciato-masala-anche-in-stato-di-liberta-per-ricettazione\/","title":{"rendered":"Arrestati dal personale della Polizia di Stato due pluripregiudicati per furto in concorso ed anche denunciato Masala anche in stato di libert\u00e0 per ricettazione"},"content":{"rendered":"<p>Gli agenti della Squadra Volanti della Questura di Cagliari hanno arrestato Franco Masala, di 45 anni residente a Carbonia e Marco Puddu di 40 anni, per furto in concorso. Masala \u00e8 stato anche denunciato in stato di libert\u00e0 per ricettazione.<\/p>\n<p>Nella serata di ieri una Volante \u00e8 stata inviata dalla Centrale Operativa in via Sassari dove un passante, tramite chiamata al 113, aveva chiesto ausilio segnalando di essere all\u2019inseguimento di due ladri, fornendo nel contempo le descrizioni dei fuggitivi e la direzione di fuga.<\/p>\n<p>I poliziotti, giunti all\u2019incrocio tra Via Sassari e Piazza del Carmine, hanno individuato i due soggetti, uno dei quali con al seguito una busta in plastica, che alla vista della macchina della Polizia hanno tentato di far perdere le tracce nascondendosi tra le auto in sosta.<\/p>\n<p>I due Pluripregiudicati, sono stati immediatamente raggiunti e bloccati ed una volta bloccati hanno controllato l\u2019interno della busta che aveva Masala dove vi era un giaccone di marca con l\u2019etichetta prezzata.<\/p>\n<p>A seguito di successive verifiche \u00e8 stato accertato che Puddu, dopo essersi introdotto in un negozio di abbigliamento, era uscito con in mano un giaccone con attaccapanni e assieme al Masala, che era rimasto all\u2019esterno fungendo da \u201cpalo\u201d, si sono allontanati in direzione Piazza Yenne. <\/p>\n<p>a accertamenti effettuati su Masala pendeva un ordine di carcerazione per scontare una pena residua di tre anni, inoltre lo stesso era in possesso di un telefono Samsung privo di scheda sim del quale non ha saputo fornire la provenienza.<\/p>\n<p>I due quindi sono stati dichiarati in arresto e su disposizione del P.M. di turno, Puddu \u00e8 stato riaccompagnato presso il proprio domicilio e Masala trattenuto presso le camere di sicurezza in attesa del processo con il rito della direttissima previsto per oggi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli agenti della Squadra Volanti della Questura di Cagliari hanno arrestato Franco Masala, di 45 anni residente a Carbonia e Marco Puddu di 40 anni,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114857"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=114857"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114857\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=114857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=114857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=114857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}