{"id":114854,"date":"2015-01-20T17:20:52","date_gmt":"2015-01-20T16:20:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/20\/01\/2015\/doppio-appuntamento-con-la-comicita-il-prossimo-marzo-a-cagliari-il-6-arrivano-ale--franz-con-il-loro-spettacolo-lavori-in-corsovenerdi-13-enrico-bertolino-con-casta-away-la-tempesta-cambiave"},"modified":"2015-01-20T17:20:52","modified_gmt":"2015-01-20T16:20:52","slug":"doppio-appuntamento-con-la-comicita-il-prossimo-marzo-a-cagliari-il-6-arrivano-ale-franz-con-il-loro-spettacolo-lavori-in-corsovenerdi-13-enrico-bertolino-con-casta-away-la-tempesta-cambiaverso","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/01\/20\/doppio-appuntamento-con-la-comicita-il-prossimo-marzo-a-cagliari-il-6-arrivano-ale-franz-con-il-loro-spettacolo-lavori-in-corsovenerdi-13-enrico-bertolino-con-casta-away-la-tempesta-cambiaverso\/","title":{"rendered":"Doppio appuntamento con la comicit\u00e0 il prossimo marzo a Cagliari: il 6 arrivano Ale &#038; Franz con il loro spettacolo &#8220;Lavori in corso&#8221;.Venerd\u00ec 13 Enrico Bertolino con &#8220;Casta Away, la tempesta #cambiaverso&#8221;."},"content":{"rendered":"<p>Doppio appuntamento con la comicit\u00e0, il prossimo marzo a Cagliari: venerd\u00ec 6 (ore 21,15), all'Auditorium del Conservatorio, arrivano Ale &amp; Franz con il loro spettacolo \"Lavori in corso\"; sette sere dopo (venerd\u00ec 13, stessa ora) \u00e8 invece di scena di Enrico Bertolino con \"Casta Away, la tempesta #cambiaverso\". Due serate tutte da ridere presentate dalla cooperativa Forma e Poesia nel Jazz.<\/p>\n<p>I biglietti si possono acquistare nei punti vendita del circuito Box Office Sardegna (tel. 070657428): un posto in platea per lo spettacolo di Ale &amp; Franz costa 34,50 euro (inclusi i diritti di prevendita); 25 euro, invece, il prezzo del biglietto per Bertolino. Previste riduzioni per ultra sessantacinquenni, minorenni e giovani tra i diciotto e i venticinque anni; mini abbonamento per le due recite e 47 euro. All'indomani delle rispettive recite cagliaritane,\"Lavori in corso\" e \"Casta Away, la tempesta #cambiaverso\" andranno in scena anche a Sassari, ma per altra organizzazione.<\/p>\n<p>In attivit\u00e0 da quasi vent'anni, Ale &amp; Franz (al secolo Alessandro Besentini e Francesco Villa) hanno legato soprattutto al piccolo schermo la loro popolarit\u00e0: dopo il debutto con lo spettacolo \"Dalla A alla Z\" e la gavetta nei locali in giro per l'Italia, le prime uscite in tv, nel 1997, in \"Facciamo Cabaret\" e \"Pippo Chennedy Show\", aprono al duo la strada di un successo consacrato negli anni a seguire attraverso programmi come \"Mai dire gol\", \"Convenscion\", \"Buona la prima\" (in onda per ben tre edizioni dal 2007 al 2009), \"Ale e Franz Sketch Show\" e, naturalmente, varie stagioni di \"Zelig\". Tanta televisione, ma anche cinema, con qualche apparizione in film come \"Bibo per sempre\", \"Tutti gli uomini del deficiente\", \"La grande prugna\", a precedere il loro primo film, \"La terza stella\" (2005); e poi \"Mi fido di te\", e ancora parti in \"Il peggior Natale della mia vita\" e i pi\u00f9 recenti \"Un fidanzato per mia moglie\" e \"Soap opera\". Televisione, cinema e, naturalmente, teatro con spettacoli come \"Due e Venti\", \"Zelig in tour\", \"Aria precaria\" e questo \"Lavori in corso\" in arrivo a Cagliari il prossimo 6 marzo; scritto da Ale &amp; Franz con Antonio De Santis, per la regia di Alberto Ferrari, alterna parti inedite a momenti del repertorio \"classico\" del duo comico, dalla panchina al noir.<\/p>\n<p>Evoca invece il titolo di un noto film con Tom Hanks lo spettacolo con cui, il 13 marzo, Enrico Bertolino ritorna a Cagliari a dodici anni dalla sua ultima esibizione nel capoluogo sardo; e come nella pellicola diretta da Robert Zemeckis (\"Cast Away\"), anche in questo \"Casta Away, la tempesta #cambiaverso\" il protagonista finisce naufrago su un'isola deserta dove ritrover\u00e0 un vecchio compagno di bagordi, un pianista sul Mediterraneo scomparso anni prima durante una crociera, al quale dovr\u00e0 dimostrare che nel frattempo tutto \u00e8 cambiato e l'Italia \u00e8 tutta nuova... Ad accompagnare sul palco il dissacrante comico milanese il maestro Teo Ciavarella. Lo spettacolo \u00e8 scritto dallo stesso Bertolino con Luca Bottura, Ugo Ripamonti e Curzio Maltese; firma la regia Massimo Navone.<\/p>\n<p>Classe 1960, una laurea in Economia alla Bocconi e un'esperienza manageriale nel campo delle risorse umane, Enrico Bertolino esordisce in tv nel 1996 su Italia 7 con \"Seven Show\", dopo una lunga gavetta cabarettistica e qualche premio, compreso il BravoGrazie. L'anno dopo debutta su Italia 1 con \"Zelig: Facciamo Cabaret\" e, poco dopo, \"Ciro, il figlio di Target\", aprendo l'intensa attivit\u00e0 televisiva che nel corso degli anni lo vedr\u00e0 impegnato, come ospite o come conduttore o tra gli interpreti, sia sulle reti Mediaset (\"Le Iene Show\", \"Ciro presenta Visitors\", \"Zelig\", \"Mai dire gol\", la sit-com \"Il supermercato\", le serie \"Piloti\", il film tv \"Non smettere di sognare\") che RAI (\"Festa di classe\", \"Convenscion\", \"Bulldozer\", \"Glob\", \"Wikitaly\"). Autore (o coautore) di diversi libri (\"Milanesi\", \"Op, Op , Op , Din, Din, Din\", \"Ho visto cose...\", \"I Manuali di autodistruzione\", \"Quarantenne sar\u00e0 lei\", \"Pirla con me\"), lo ritroviamo anche sul grande schermo (tra gli interpreti dei film \"Incontri proibiti\", \"E allora mambo!\", \"La grande prugna\", \"Tandem\", \"Un'estate ai Caraibi\" e \"Ti amo troppo per dirtelo\"), e naturalmente in teatro: tra il 1998 e il 1999 \u00e8 in scena con gli spettacoli \"D\u2019altra parte \u00e8 cos\u00ec\" e \"The day after\"; poi con \"Il diluvio fa bene ai gerani\" (applaudito anche a Cagliari nel 2003), \"Voti a perdere\" (tra il 2005 e il 2006), \"Lampi accecanti di Ovviet\u00e0\" (2008), \"Passata \u00e8 la tempesta? Nuovi lampi di ovviet\u00e0\" (2010\/2011) e l'ultimo \"Casta Away, la tempesta #cambiaverso\" atteso nel capoluogo sardo il prossimo 13 marzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doppio appuntamento con la comicit\u00e0, il prossimo marzo a Cagliari: venerd\u00ec 6 (ore 21,15), all&#8217;Auditorium del Conservatorio, arrivano Ale &amp; Franz con il loro spettacolo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114854"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=114854"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114854\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=114854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=114854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=114854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}