{"id":114838,"date":"2015-01-21T17:20:52","date_gmt":"2015-01-21T16:20:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/21\/01\/2015\/provincia-di-nuoro---realizzazione-di-due-centrali-termiche-alimentate-con-cippato-in-due-edifici-scolastici"},"modified":"2015-01-21T17:20:52","modified_gmt":"2015-01-21T16:20:52","slug":"provincia-di-nuoro-realizzazione-di-due-centrali-termiche-alimentate-con-cippato-in-due-edifici-scolastici","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/01\/21\/provincia-di-nuoro-realizzazione-di-due-centrali-termiche-alimentate-con-cippato-in-due-edifici-scolastici\/","title":{"rendered":"Provincia di Nuoro &#8211; Realizzazione di due centrali termiche alimentate con Cippato in due edifici scolastici."},"content":{"rendered":"<p>La Giunta provinciale di Nuoro, presieduta dal Presidente Costantino Tidu, ha approvato il Progetto definitivo-esecutivo inserito nel programma comunitario Biomass+ per la realizzazione di due centrali termiche alimentate con Cippato di legno, presso l\u2019Istituto Tecnico Commerciale Maxia di Aritzo ed il Liceo Costa Azara di Sorgono.<\/p>\n<p>Il progetto consiste nell\u2019installazione di due nuove caldaie a biomassa nei due istituti scolastici di propriet\u00e0 della Provincia, scelti sulla base delle caratteristiche di boscosit\u00e0 dell\u2019area in cui si trovano, e l\u2019obiettivo \u00e8 quello di promuovere lo sviluppo della filiera corta in maniera economicamente funzionale attraverso l\u2019utilizzo delle biomasse agro forestali provenienti dai territori limitrofi, non contaminate da sostanze chimiche o inquinanti.<\/p>\n<p>\u201cQuesto progetto ci consente di realizzare impianti finalizzati alla produzione di calore, a servizio degli impianti di riscaldamento dei due istituti scolastici, utilizzando materie prime naturali rinnovabili e riducendo cos\u00ec la dipendenza dalle fonti tradizionali, come il petrolio e il gas - ha spiegato l\u2019assessore all\u2019Ambiente e all\u2019Energia della Provincia di Nuoro, Paolo Porcu \u2013&nbsp; in questo modo sar\u00e0 possibile garantire la sicurezza degli approvvigionamenti grazie all\u2019indipendenza da fornitori esterni potendo contare su energia in loco e recuperando prodotti agricoli residui. Inoltre - ha sottolineato l\u2019assessore Porcu - l\u2019attivit\u00e0, che \u00e8 stata oggetto di uno studio fatto dagli studenti della 4\u00b0A dell\u2019ITC di Aritzo, premiato dal Banco di Sardegna nel 2010, pu\u00f2 creare un indotto economico attorno all\u2019impianto e quindi posti di lavoro sul territorio\u201d.<\/p>\n<p>L\u2019intervento nello specifico prevede l\u2019installazione di due caldaie per riscaldamento da 350 KW per Aritzo e 250 KW per Sorgono con una riduzione dei costi per il combustibile prevista pari a circa il 50 % circa.<\/p>\n<p>I lavori sono stati consegnati lo scorso 15 gennaio 2015 e dovranno essere conclusi entro il mese di maggio. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Giunta provinciale di Nuoro, presieduta dal Presidente Costantino Tidu, ha approvato il Progetto definitivo-esecutivo inserito nel programma comunitario Biomass+ per la realizzazione di due&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114838"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=114838"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114838\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=114838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=114838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=114838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}