{"id":114813,"date":"2015-01-23T17:20:52","date_gmt":"2015-01-23T16:20:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/23\/01\/2015\/trasporti-20-milioni-per-adeguamento-rete-ferroviaria-firmata-convenzione-ras-rfi"},"modified":"2015-01-23T17:20:52","modified_gmt":"2015-01-23T16:20:52","slug":"trasporti-20-milioni-per-adeguamento-rete-ferroviaria-firmata-convenzione-ras-rfi","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/01\/23\/trasporti-20-milioni-per-adeguamento-rete-ferroviaria-firmata-convenzione-ras-rfi\/","title":{"rendered":"Trasporti: 20 milioni per adeguamento rete ferroviaria. Firmata convenzione Ras-Rfi"},"content":{"rendered":"<p>Venti milioni per migliorare le ferrovie sarde. Oggi \u00e8 stata firmata una convenzione tra l\u2019assessorato dei Trasporti e la societ\u00e0 Rete Ferroviaria Italiana che prevede importanti interventi di potenziamento della sicurezza e di rafforzamento delle condizioni infrastrutturali. I lavori, finanziati con i fondi del Piano di Azione Coesione, si concluderanno entro il 2019 e verranno eseguiti nelle linee Oristano - Golfo Aranci, Chilivani - Porto Torres e Decimomannu - Iglesias - Carbonia. Consentiranno di dotare la rete in queste tratte del sistema di segnalamento S.C.M.T. (Sistema di Controllo della Marcia del Treno).<\/p>\n<p>\u201cLa scelta di puntare sulla ferrovia quale asse portante del nuovo sistema di mobilit\u00e0 isolano continua a consolidarsi anche con la firma della convenzione odierna con Rfi\u201d, commenta l\u2019assessore dei Trasporti, Massimo Deiana. \u201cAlla fine degli interventi la rete della Sardegna sar\u00e0 dotata di un moderno sistema tecnologico di segnalamento che consentir\u00e0 di aumentare il grado di sicurezza dell\u2019infrastruttura, di incrementare in modo significativo la velocit\u00e0 dei treni, e quindi di ridurre i tempi di percorrenza\u201d, aggiunge l\u2019assessore. \u201cCrediamo che interventi come questo possano anche rispondere alle preoccupazioni, sollevate da pi\u00f9 parti, circa l\u2019adeguamento della rete a svolgere appieno un ruolo da protagonista\u201d, conclude Massimo Deiana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venti milioni per migliorare le ferrovie sarde. Oggi \u00e8 stata firmata una convenzione tra l\u2019assessorato dei Trasporti e la societ\u00e0 Rete Ferroviaria Italiana che prevede&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114813"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=114813"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114813\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=114813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=114813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=114813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}