{"id":114729,"date":"2015-01-28T17:20:52","date_gmt":"2015-01-28T16:20:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/28\/01\/2015\/bonifiche-dei-siti-minerari-verso-una-collaborazione-tra-comuni-e-igea"},"modified":"2015-01-28T17:20:52","modified_gmt":"2015-01-28T16:20:52","slug":"bonifiche-dei-siti-minerari-verso-una-collaborazione-tra-comuni-e-igea","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/01\/28\/bonifiche-dei-siti-minerari-verso-una-collaborazione-tra-comuni-e-igea\/","title":{"rendered":"Bonifiche dei siti minerari, verso una collaborazione tra comuni e Igea"},"content":{"rendered":"<p>Le bonifiche delle aree minerarie dismesse nel Sulcis e nel Guspinese sono una priorit\u00e0 nel programma di governo della Giunta Regionale. Il tema \u00e8 stato affrontato anche oggi, insieme ai sindaci e ai sindacati, nel corso dell\u2019incontro svoltosi a Cagliari sullo stato di attuazione del Piano Sulcis.<\/p>\n<p>Le note vicende che hanno riguardato Igea, l\u2019avvicendarsi dei liquidatori e le difficolt\u00e0 finanziarie della societ\u00e0, imponevano di valutare diversi scenari, tra cui anche quello prioritario di salvaguardare la stessa Igea e di verificare la capacit\u00e0 di riorganizzarsi per realizzare autonomamente gli interventi previsti. Nel corso degli incontri di questi giorni, ha prevalso la scelta di rendere partecipi nei progetti di bonifica i Comuni interessati, con l\u2019obiettivo di valutare anche il coinvolgimento operativo di Igea. In questa prospettiva, la Giunta esaminer\u00e0 presto un provvedimento.<\/p>\n<p>\u201cGli assessori e la Giunta hanno un unico obiettivo \u2013 afferma l\u2019assessore dell\u2019Industria, Maria Grazia Piras \u2013 avviare la fase di risanamento dei siti compromessi, per restituire i territori alle intraprese economiche, e fare le bonifiche nel pi\u00f9 breve tempo possibile, coinvolgendo tutte le risorse e gli operatori del territorio, compresa Igea, avviata nella fase di riorganizzazione e di ristrutturazione\u201d.<\/p>\n<p>&nbsp;\u201cLe comunit\u00e0 del Sulcis \u2013 concorda l\u2019assessore dell\u2019Ambiente Donatella Spano \u2013 non possono pi\u00f9 attendere l\u2019attuazione degli interventi di bonifica e la restituzione dei territori risanati. Questo rappresenta l\u2019impegno che la Giunta ha unanimemente assunto con il territorio e con i Comuni interessati\u201d. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le bonifiche delle aree minerarie dismesse nel Sulcis e nel Guspinese sono una priorit\u00e0 nel programma di governo della Giunta Regionale. Il tema \u00e8 stato&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114729"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=114729"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114729\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=114729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=114729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=114729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}