{"id":114686,"date":"2015-01-31T17:20:52","date_gmt":"2015-01-31T16:20:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/31\/01\/2015\/istat-cala-la-disoccupazione--04-dato-migliore-dal-2011"},"modified":"2015-01-31T17:20:52","modified_gmt":"2015-01-31T16:20:52","slug":"istat-cala-la-disoccupazione-04-dato-migliore-dal-2011","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/01\/31\/istat-cala-la-disoccupazione-04-dato-migliore-dal-2011\/","title":{"rendered":"Istat, cala la disoccupazione: -0,4%, dato migliore dal 2011."},"content":{"rendered":"<p>Dopo mesi di cattive notizie il mercato del lavoro ne registra una positiva: a dicembre ci sono stati 93 mila occupati in pi\u00f9, un aumento del 4% che porta il totale a 22 milioni e 422 mila. A dirlo sono i dati Istat diffusi oggi.<\/p>\n<p>Il numero di disoccupati, pari a 3 milioni 322 mila, diminuisce del 3,2% rispetto al mese precedente (-109 mila).&nbsp; A fare salire il numero dei nuovi occupati potrebbero per\u00f2 essere i lavori temporanei natalizi che, in effetti, durano solo per il mese di dicembre. Da confrontare, quindi, con i numeri di gennaio. Ad ogni modo su base annua i dati non sono certo positivi: 95 mila persone - il 2,9% in pi\u00f9 rispetto al 2013 - hanno perso il lavoro.<\/p>\n<p>Eppure, considerando il contesto, si tratta del calo pi\u00f9 significativo dal 2011. E pochi secondi dopo arriva l'approvazione del premier Matteo Renzi.<\/p>\n<p>A dicembre quasi met\u00e0 dei giovani italiani \u00e8 senza lavoro, il 42%. Anche qui: dato preoccupante ma rispetto al passato recente positivo perch\u00e9 su base mensile \u00e8 sceso di un punto.<\/p>\n<p>Il numero di individui inattivi tra i 15 e i 64 anni aumenta a dicembre: 14 milioni e 106 mila persone, in aumento dello 0,2% rispetto al mese precedente (+28 mila). Il tasso di inattivit\u00e0, pari al 35,8%, aumenta di 0,1 punti percentuali in termini congiunturali e diminuisce di 0,6 punti su base annua. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo mesi di cattive notizie il mercato del lavoro ne registra una positiva: a dicembre ci sono stati 93 mila occupati in pi\u00f9, un aumento&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114686"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=114686"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114686\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=114686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=114686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=114686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}