{"id":114664,"date":"2015-02-02T17:20:52","date_gmt":"2015-02-02T16:20:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/02\/02\/2015\/oristano--consegnate-candele-benedette-durante-la-cerimonia-della-candelora"},"modified":"2015-02-02T17:20:52","modified_gmt":"2015-02-02T16:20:52","slug":"oristano-consegnate-candele-benedette-durante-la-cerimonia-della-candelora","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/02\/02\/oristano-consegnate-candele-benedette-durante-la-cerimonia-della-candelora\/","title":{"rendered":"Oristano \u2013 Consegnate candele benedette durante la cerimonia della Candelora"},"content":{"rendered":"<p>Questa mattina presso la Questura di Oristano, i rappresentanti dei Gremi dei Contadini, dei Falegnami e dei muratori, hanno consegnato al Questore di<\/p>\n<p>Oristano, Francesco Angelo Di Ruberto le candele Benedette durante la cerimonia della candelora, come segno di buon auspicio per il&nbsp; 2015.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa mattina presso la Questura di Oristano, i rappresentanti dei Gremi dei Contadini, dei Falegnami e dei muratori, hanno consegnato al Questore di Oristano, Francesco&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114664"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=114664"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114664\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=114664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=114664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=114664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}