{"id":114661,"date":"2015-02-02T17:20:52","date_gmt":"2015-02-02T16:20:52","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/02\/02\/2015\/maltempo---il-nord-sardegna-chiuso-per-neve-scuole-chiuse-a-nuoro-neve-e-freddo-su-tutta-la-penisola"},"modified":"2015-02-02T17:20:52","modified_gmt":"2015-02-02T16:20:52","slug":"maltempo-il-nord-sardegna-chiuso-per-neve-scuole-chiuse-a-nuoro-neve-e-freddo-su-tutta-la-penisola","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2015\/02\/02\/maltempo-il-nord-sardegna-chiuso-per-neve-scuole-chiuse-a-nuoro-neve-e-freddo-su-tutta-la-penisola\/","title":{"rendered":"Maltempo &#8211; Il Nord Sardegna chiuso per neve: scuole chiuse a Nuoro, neve e freddo su tutta la penisola"},"content":{"rendered":"<p>Ieri notte, la neve \u00e8 caduta in modo intenso nel centro nord della Sardegna. Nuoro si \u00e8 svegliata imbiancata e il sindaco Alessandro Bianchi ha annunciato l'interruzione delle lezioni in tutte le scuole della citt\u00e0. Stessa decisione anche a Cagliari e Potenza dove la neve sta creando rallentamenti alla circolazione automobilistica, anche se tutte le principali arterie della regione risultano percorribili.<\/p>\n<p>Vesuvio ricoperto di neve dalla cima alle pendici: in queste ore le temperature pi\u00f9 fredde e le piogge battenti su Napoli e provincia hanno determinato la formazione di un fitto strato nevoso visibile dalle abitazioni della fascia vesuviana. Alle quote pi\u00f9 basse la grandine ha reso bianchi giardini e tetti delle case. Oltre 50 interventi sono stati effettuati dai vigili del fuoco a Napoli e provincia. Caduta di intonaci, infiltrazioni d'acqua, rami pericolanti e verifiche di staticit\u00e0 in diversi quartieri del capoluogo e in provincia, in particolare a San Giorgio a Cremano, Ercolano e torre annunziata. E in Campania si cercano volontari per spalare il fango. La richiesta \u00e8 stata lanciata in queste ore dalla protezione civile del comune di capaccio Paestum (Salerno) dopo lo straripamento del fiume Sele che nella giornata di ieri ha colpito il centro della piana omonima.<\/p>\n<p>Nevica ancora in Calabria al di sopra dei 500 metri e, in particolare sui rilievi. Nel resto della regione dominano la pioggia, il vento e le temperature basse. Situazione sempre critica nel crotonese, a Petilia Policastro, dove una frana, nella frazione foresta, ha provocato il crollo di una palazzina creando problemi ad altre abitazioni vicine. Trentacinque persone hanno dovuto abbandonare la loro casa per essere ospitate in abitazioni messe a disposizione da concittadini.<\/p>\n<p>Torna il rischio valanghe in montagna: in Alto Adige pericolo valanghe rimane marcato, di grado 3 in una scala da 1 a 5. Massima allerta per elevato rischio valanghe \u00e8 stata diramata anche dal soccorso alpino di Calabria e Basilicata, in particolare per il massiccio del pollino, dove una valanga di grande dimensioni sul monte Sirino ha divelto i piloni della seggiovia. Acqua alta a Venezia l'acqua alta \u00e8 tornata stamane a Venezia con una punta massima di un metro e 14 centimetri sopra il medio mare. Si tratta delle misura maggiore segnata dal fenomeno in questa prima parte del 2015.<\/p>\n<p>Neve abbondante in Molise, dove \u00e8 caduta durante la notte gi\u00e0 a quote collinari. Stamane tanti sciatori in montagna e impianti aperti sia a Campitello Matese (Campobasso) che a Capracotta (Isernia). Cinque centimetri di neve anche a Campobasso.&nbsp; Nevicata stamani su alcune delle principali strade umbre, in particolare quelle dell'appennino al confine con le marche. Continua a nevicare all'aquila e nella marsica, mentre sulle autostrade a24 Roma-Teramo e a25 Torano-Pescara viene segnalato nevischio. Le temperature restano intorno allo zero nell'entroterra, mentre sulla costa oscillano tra i 9 gradi di Pescara e i 13 di vasto (Chieti).<\/p>\n<p>Cessata con qualche ora di anticipo l'allerta meteo per neve in Toscana, \u00e8 ora rischio ghiaccio, che fino a domani mattina potrebbe formarsi a causa del repentino calo termico atteso al calar del sole. Oggi vi sono stati rovesci sulla fascia costiera centro meridionale e sull'arcipelago, in casentino, val di chiana e maremma. Nevicate a quote collinari, localmente a quote inferiori in maremma. Possibili mareggiate inoltre, dalle prime ore di oggi, la protezione civile prevede ancora venti forti o di burrasca, con raffiche di burrasca forte, su Sardegna, Sicilia e Calabria, con possibili mareggiate lungo le coste esposte previsioni per le prossime ore nelle prossime ore \u00e8 previsto un ulteriore calo delle temperature. Al nord nubi in ulteriore aumento con deboli fenomeni nevosi a bassa quota; piogge anche su Romagna e Friuli. Al centro peggiora con nuvolosit\u00e0 e fenomeni in marcia dal tirreno verso l'adriatico e nevicate oltre i 200\/700m.<\/p>\n<p>emperature senza variazioni, massime tra 5 e 10. Al sud ancora maltempo sulle tirreniche con fenomeni in sconfinamento, attenuati, al basso adriatico; neve in rialzo oltre i 1000m. temperature in rialzo, massime tra 9 e 14. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ieri notte, la neve \u00e8 caduta in modo intenso nel centro nord della Sardegna. Nuoro si \u00e8 svegliata imbiancata e il sindaco Alessandro Bianchi ha&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114661"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=114661"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/114661\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=114661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=114661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=114661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}