{"id":107061,"date":"2013-11-13T17:20:44","date_gmt":"2013-11-13T16:20:44","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/13\/11\/2013\/premi-ussi-sardegna-2013-sport-come-integrazione-e-salute"},"modified":"2013-11-13T17:20:44","modified_gmt":"2013-11-13T16:20:44","slug":"premi-ussi-sardegna-2013-sport-come-integrazione-e-salute","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/13\/premi-ussi-sardegna-2013-sport-come-integrazione-e-salute\/","title":{"rendered":"Premi Ussi Sardegna 2013: \u201cSport come Integrazione e Salute\u201d"},"content":{"rendered":"<p>Gigi Riva, gli eroi dello scudetto del \u201970, Gigi Datome, Promogest, Fabio Aru e Daniele Conti tra i premiati. Interventi del ministro dell\u2019Integrazione e del presidente del Coni all\u2019evento dedicato ad atleti e club di pregio<BR>Attualit\u00e0 e cerimonia. Un tema attuale come l'immigrazione, che in questa occasione si lega allo sport e alla salute, non poteva che richiedere testimonial di alto profilo. Tra questi, il ministro dell\u2019Integrazione, C\u00e8cile Kyenge, e il presidente del Coni nazionale, Giovanni Malag\u00f2, dai quali il direttivo dell'Ussi (Unione Stampa Sportiva Italiana) ha ottenuto il patrocinio e un intervento per la cerimonia di consegna dei Premi Ussi Sardegna 2013, in programma sabato 16 novembre alle 10.30 nella palestra del Cus Cagliari, via Is Mirrionis, n. 3, sa Duchessa.<\/p>\n<p>L'appuntamento - a cui hanno aderito le massime cariche istituzionali, politiche e sportive, con Presidenza della Giunta regionale, assessorato regionale allo Sport, Cusi (Centro italiano sport universitario), comune di Cagliari, Coni, Ordine dei giornalisti, corso di laurea in Scienze della comunicazione patrocinatori dell\u2019evento - prevede riconoscimenti per Gigi Riva con al fianco i compagni dei tempi dello scudetto Tomasini, Poli, Greatti, Brugnera, Reginato, Daniele Conti e altri atleti e societ\u00e0 isolane, ma non solo, che si sono distinti nell\u2019ultima stagione. Tra questi Ouslid Abdelkaber Amsicora, Fabio Aru, Veronica Baldaccini Angelo Binaghi, Manuel Cappai, Centro di coordinamento dei Cagliari club, Leonardo Coiana, Gigi Datome, Dinamo Sassari, Donatella Faedda, Claudia Pinna, Fabio Poddighe, Promogest, Falou Samb, Special Olimpics, Team solidale, Torres calcio femminile.<\/p>\n<p>Alla cerimonia interviene anche il campione del mondo Bruno Conti. E sono previsti video di figure di rilievo internazionale quali Valeria Straneo (vice campione del mondo di maratona, ottava a Londra 2012) e le vincitrici&nbsp; della Fed Cup 2013. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gigi Riva, gli eroi dello scudetto del \u201970, Gigi Datome, Promogest, Fabio Aru e Daniele Conti tra i premiati. Interventi del ministro dell\u2019Integrazione e del&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/107061"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=107061"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/107061\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=107061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=107061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=107061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}