{"id":107052,"date":"2013-11-11T17:20:44","date_gmt":"2013-11-11T16:20:44","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/11\/11\/2013\/arrestati-due-giovani-stranieri-per-furto-aggravato"},"modified":"2013-11-11T17:20:44","modified_gmt":"2013-11-11T16:20:44","slug":"arrestati-due-giovani-stranieri-per-furto-aggravato","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/11\/arrestati-due-giovani-stranieri-per-furto-aggravato\/","title":{"rendered":"Arrestati due giovani stranieri per furto aggravato"},"content":{"rendered":"<p>I carabinieri della Stazione di Ca-Sant\u2019Avendrace, hanno arrestato presso il centro commerciale \u201cAuchan \u2013 Santa Gilla\u201d,&nbsp; per furto aggravato&nbsp; Linda Ivanova, di 22 anni, della Slovaccha, senza fissa dimora,&nbsp; nullafacente e Pascual Nicola, 25 anni, anche questo senza fissa dimora.<\/p>\n<p>I due giovani, all\u2019interno del centro commerciale, dopo averne asportato i sistemi antitaccheggio, si sono impossessati di 10 confezioni di bottarga e un reggiseno, per un valore complessivo di 250,00 euro, oltrepassando la barriera delle casse senza pagare il dovuto.<\/p>\n<p>I due quindi sono stati bloccati dal personale della sicurezza che poi sono stati consegnati ai militari dell\u2019Arma che una volta portati in caserma, dopo le formalit\u00e0 di rito, li hanno trattenuti nelle camere di sicurezza della Stazione cc Ca- Villanova, in attesa del rito direttissimo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri della Stazione di Ca-Sant\u2019Avendrace, hanno arrestato presso il centro commerciale \u201cAuchan \u2013 Santa Gilla\u201d,&nbsp; per furto aggravato&nbsp; Linda Ivanova, di 22 anni, della&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/107052"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=107052"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/107052\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=107052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=107052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=107052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}