{"id":107029,"date":"2013-11-04T17:20:44","date_gmt":"2013-11-04T16:20:44","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/04\/11\/2013\/quattro-novembre-presidente-regione-sardegna-ideali-brigata-sassari-dono-e-monito-per-tutti"},"modified":"2013-11-04T17:20:44","modified_gmt":"2013-11-04T16:20:44","slug":"quattro-novembre-presidente-regione-sardegna-ideali-brigata-sassari-dono-e-monito-per-tutti","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/04\/quattro-novembre-presidente-regione-sardegna-ideali-brigata-sassari-dono-e-monito-per-tutti\/","title":{"rendered":"Quattro novembre: Presidente Regione Sardegna, ideali Brigata Sassari dono e monito per tutti."},"content":{"rendered":"<p>\u201cGiornate come questa ricordano a tutti noi i valori per cui la Brigata Sassari ha combattuto in passato e per i quali ancora oggi dimostra tutto il suo coraggio: la pace, la fratellanza, la possibilit\u00e0 di vivere in una comunit\u00e0 che non sia lacerata dalla tragedia della guerra\u201d. <\/p>\n<p>Lo ha dichiarato il presidente della Regione Ugo Cappellacci intervenendo questo pomeriggio ad Asiago alla cerimonia in ricordo dei martiri della Brigata Sassari. \u201cQuesto \u00e8 il dono - ha aggiunto Cappellacci - che hanno lasciato a tutti noi e che dobbiamo essere capaci di custodire per consegnarlo alle future generazioni.&nbsp; Quell'ideale di patria e di libert\u00e0 \u00e8 un testimone passato ora nelle mani dei nostri ragazzi della Sassari, che in questi anni hanno dato prova del loro coraggio e della loro professionalit\u00e0 durante le missioni di pace in terra straniera. Il loro esempio, insieme alla memoria di chi ha sacrificato la vita, - ha concluso il presidente- \u00e8 un monito per tutti noi\u201d.<\/p>\n<p>Alla cerimonia sono intervenuti, tra gli altri, Antonio Quartu, sindaco di Armungia, paese natale di Emilio Lussu, e Antonio Pinna, consulente del comitato dei comuni della Sardegna impegnati nel recupero dei siti storici della Brigata Sassari. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cGiornate come questa ricordano a tutti noi i valori per cui la Brigata Sassari ha combattuto in passato e per i quali ancora oggi dimostra&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/107029"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=107029"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/107029\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=107029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=107029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=107029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}