{"id":107015,"date":"2013-11-11T17:20:44","date_gmt":"2013-11-11T16:20:44","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/11\/11\/2013\/sgominata-baby-gang-di-olbia-in-comunita-per-minori-un-14enne-di-olbia"},"modified":"2013-11-11T17:20:44","modified_gmt":"2013-11-11T16:20:44","slug":"sgominata-baby-gang-di-olbia-in-comunita-per-minori-un-14enne-di-olbia","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/11\/sgominata-baby-gang-di-olbia-in-comunita-per-minori-un-14enne-di-olbia\/","title":{"rendered":"Sgominata Baby gang di Olbia, in comunit\u00e0 per minori un 14enne di Olbia."},"content":{"rendered":"<p>Quest\u2019oggi, i Carabinieri del Reparto Territoriale di Olbia, hanno dato&nbsp; esecuzione ad un\u2019Ordinanza di collocamento in comunit\u00e0 nei confronti di un 14enne della citt\u00e0, emessa dal G.I.P. del Tribunale dei Minorenni di Sassari.<\/p>\n<p>Gli episodi contestati sono quelli relativi alla cosiddetta Baby gang di Olbia, pare composta da una decina tra ragazzini e ragazzine dai 13 ai 17 anni, che intimorivano loro coetanei con vessazioni ed angherie.<\/p>\n<p>L\u2019episodio per il quale oggi si \u00e8 proceduto \u00e8 quello relativo alla rapina patita da una quindicenne alla quale, dopo percosse ed insulti, la piccola vittima aveva portato via un cellulare di ultima generazione.<\/p>\n<p>Il risultato di quest\u2019oggi \u00e8 frutto di un\u2019attivit\u00e0 investigativa serrata dei Carabinieri del Reparto Territoriale, che ha permesso alla Procura della Repubblica presso il Tribunale dei Minorenni di richiedere ed ottenere una misura coercitiva forte nei confronti di una giovane resasi responsabile di un fatto gravissimo.<BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest\u2019oggi, i Carabinieri del Reparto Territoriale di Olbia, hanno dato&nbsp; esecuzione ad un\u2019Ordinanza di collocamento in comunit\u00e0 nei confronti di un 14enne della citt\u00e0, emessa&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/107015"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=107015"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/107015\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=107015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=107015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=107015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}