{"id":106998,"date":"2013-11-14T17:20:44","date_gmt":"2013-11-14T16:20:44","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/14\/11\/2013\/ocse-i-manager-pubblici-italiani-i-piu-pagati-al-mondo"},"modified":"2013-11-14T17:20:44","modified_gmt":"2013-11-14T16:20:44","slug":"ocse-i-manager-pubblici-italiani-i-piu-pagati-al-mondo","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/14\/ocse-i-manager-pubblici-italiani-i-piu-pagati-al-mondo\/","title":{"rendered":"Ocse: &#8220;I manager pubblici italiani i pi\u00f9 pagati al mondo&#8221;"},"content":{"rendered":"<p>I dirigenti della pubblica amministrazione italiana sono i pi\u00f9 pagati dell\u2019area Ocse. Con il loro stipendio medio di 650 mila dollari l\u2019anno guadagnano poco meno del doppio dei secondi classificati, i neozelandesi, e quasi il triplo rispetto alla media Ocse ferma a 232 mila dollari. E\u2019 quanto emerge dal rapporto comparativo \u201cGovernment at a glance 2013\u201d presentato dall\u2019Ocse a Parigi. Tra i dati dell\u2019Organizzazione per la cooperazione e lo sviluppo economico non solo stipendi ma anche sviluppo dell\u2019e-government, fiducia nelle istituzioni e peso della spesa pubblica.<\/p>\n<p>I senior manager della pubblica amministrazione centrale italiana sono i pi\u00f9 pagati dell'area Ocse con uno stipendio medio di 650 mila dollari, oltre 250 mila in pi\u00f9 dei secondi classificati (i neozelandesi con 397 mila dollari) e quasi il triplo della media Ocse (232 mila dollari). I dati sono aggiornati al 2011 e, per un confronto, basti pensare che in Francia, un dirigente dello stesso livello, guadagna in media 260 mila dollari all'anno, in Germania 231 mila e in Gran Bretagna 348 mila. Negli Stati Uniti, la retribuzione media \u00e8 di 275 mila dollari.<\/p>\n<p>In Italia solo il 28% dei cittadini ha fiducia nel governo, e la percentuale \u00e8 diminuita di 2 punti dal 2007. Il dato italiano \u00e8 ben al di sotto della media dei Paesi dell'organizzazione (40%), e delle percentuali registrate in Francia (44%), Germania (42%) e Gran Bretagna (47%). In testa alla classifica della fiducia nei loro governi ci sono Svizzera (77%) e Lussemburgo (74%), in coda Grecia (13%), Giappone e Repubblica Ceca (17%). Gli italiani hanno poca fiducia anche nel sistema giudiziario (38% contro una media Ocse del 51%) e in quello sanitario (55% contro 71%), mentre ne hanno molta nella polizia locale (76% contro 72%). Le misure di austerit\u00e0 adottate da molti Paesi dopo la crisi economica hanno contribuito all'erosione della fiducia dei cittadini nei loro governanti, scesa dal 2007 al 2012 dal 45% al 40%, \"rendendo difficile per le autorit\u00e0 nazionali a mobilitare il sostegno per le necessarie riforme\". \"Serve un nuovo approccio al governo pubblico, dal momento che i governi sono chiamati a soddisfare le aspettative dei cittadini con mezzi limitati\", sostiene l'Ocse, \"un approccio costruito intorno alla creazione di capacit\u00e0 strategica, istituzioni forti, strumenti efficaci e risultati misurabili in modo chiaro\".<\/p>\n<p>Male l'Italia anche per quanto riguarda l'utilizzo di Internet nei rapporti con la pubblica amministrazione. Secondo il rapporto comparativo dell'organizzazione parigina, solo il 19% dei cittadini italiani usano la rete per interagire con enti locali e governo centrale, contro una media Ocse del 50%. Solo il Cile, con il 7%, ha un risultato peggiore, mentre tutti i grandi Paesi europei sono al di sopra del 40%: la Gran Bretagna al 43%, la Spagna al 45%, la Germania al 51% e la Francia al 61%. Nella classifica non \u00e8 incluso il Giappone, per cui non erano disponibili dati aggiornati. La percentuale di utilizzatori di servizi di e-government cresce nettamente per quanto riguarda le imprese, al 76%, ma resta la penultima tra i Paesi Ocse, davanti alla sola Svizzera, e nettamente inferiore alla media, che si attesta all'88%.<\/p>\n<p>La spesa pubblica italiana nel 2011 arrivava quasi al 50% del Pil, contro il 45,4% della media Ocse e il debito pubblico al 120%, oltre 40 punti percentuali in pi\u00f9 della media (79%). In dettaglio in Italia sono superiori alla media le spese in welfare (41% contro 35,6%) e i servizi pubblici generali (17,3% contro 13,6%); inferiori alla media le spese in educazione (8,5% contro 12,5%) e difesa (3% contro 3,9%).<\/p>\n<p>Il nostro Paese \u00e8, insieme a Messico, Grecia e Turchia, quello pi\u00f9 deve migliorare l'applicazione delle leggi. Dall'altro lato della classifica figurano invece Svezia, Giappone e Danimarca. La penisola \u00e8, inoltre, uno dei membri dell'Ocse dove per i cittadini \u00e8 pi\u00f9 difficile avere accesso alla giustizia civile (va peggio solo in Messico e Turchia), che \u00e8 invece pi\u00f9 agevole nei paesi scandinavi. L\u2019Italia \u00e8 poi il Paese dell'area Ocse con i tempi della giustizia pi\u00f9 lunghi, con una media di quasi 600 giorni di durata per un processo. <\/p>\n<p>I tribunali pi\u00f9 rapidi, invece, si trovano in Corea del Sud, Austria e Giappone, maglia rosa con una durata media dei processi di poco superiore ai 100 giorni, un primato che giustifica la presenza di Tokyo al vertice anche della classifica dei Paesi dove un procedimento richiede le spese legali maggiore. Al secondo e al terzo posto della classifica di chi spende pi\u00f9 in avvocati si trovano poi gli slovacchi e gli stessi italiani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I dirigenti della pubblica amministrazione italiana sono i pi\u00f9 pagati dell\u2019area Ocse. Con il loro stipendio medio di 650 mila dollari l\u2019anno guadagnano poco meno&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106998"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=106998"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106998\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=106998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=106998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=106998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}