{"id":106968,"date":"2013-11-07T17:20:43","date_gmt":"2013-11-07T16:20:43","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/07\/11\/2013\/we-love-sud-presidente-regione-sardegna-zona-franca-e-nostra-sfida-per-competitivita"},"modified":"2013-11-07T17:20:43","modified_gmt":"2013-11-07T16:20:43","slug":"we-love-sud-presidente-regione-sardegna-zona-franca-e-nostra-sfida-per-competitivita","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/07\/we-love-sud-presidente-regione-sardegna-zona-franca-e-nostra-sfida-per-competitivita\/","title":{"rendered":"We Love Sud. Presidente Regione Sardegna: zona franca \u00e8 nostra sfida per competitivit\u00e0"},"content":{"rendered":"<p>\u201cLa zona franca \u00e8 uno strumento importante nella sfida per la competitivit\u00e0\u201d. Lo ha dichiarato il presidente Cappellacci, intervenendo questa sera al convegno dei giovani di Confindustria \u201cWe love Sud\u201d. <BR>\u201cPer fare impresa \u2013 ha aggiunto Cappellacci - occorrono capitale umano, finanziamenti, ma anche e soprattutto un sistema capace di creare condizioni per un esercizio proficuo dell\u2019attivit\u00e0 dell\u2019azienda.<\/p>\n<p>Nell\u2019immediato dobbiamo recuperare gli svantaggi derivanti dalla condizione di insularit\u00e0, ma allo stesso tempo la zona franca integrale \u00e8 altres\u00ec azione di prospettiva, idonea a rendere la nostra Regione il ponte d\u2019Italia e d\u2019Europa verso il Mediterraneo. La fiscalit\u00e0 di vantaggio \u2013 ha osservato Cappellacci - permette di recuperare una parte rilevante del divario sofferto e sviluppare potenzialit\u00e0 finora inespresse.<\/p>\n<p>I sardi \u2013 ha evidenziato il presidente - nonostante le difficolt\u00e0, in questi decenni sono stati capaci anche di essere promotori di eccellenze. Questo significa che, laddove il sistema diventasse pi\u00f9 funzionale all\u2019attivit\u00e0 di impresa, potremmo finalmente diventare conquistatori dei mercati nazionali ed internazionali. Il ragionamento nasce dal fatto \u2013 ha spiegato Cappellacci- che rispetto agli altri costi quello derivante dal fisco sono quelli sui quali possiamo intervenire subito.<\/p>\n<p>\u00c8 la prosecuzione di quello che abbiamo fatto \u2013 ha ricordato il presidente - con quell\u2019abbattimento dell\u2019IRAP del 70%, che dobbiamo ora difendere in sede nazionale. Ora lo Stato si deve pronunciare sulla zona franca integrale \u2013 ha concluso il presidente - e fare propria in Europa la giusta rivendicazione della Sardegna\u201d. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa zona franca \u00e8 uno strumento importante nella sfida per la competitivit\u00e0\u201d. Lo ha dichiarato il presidente Cappellacci, intervenendo questa sera al convegno dei giovani&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106968"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=106968"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106968\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=106968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=106968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=106968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}