{"id":106911,"date":"2013-11-13T17:20:43","date_gmt":"2013-11-13T16:20:43","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/13\/11\/2013\/per-lo-sciopero-generale-nazionale-di-venerdi-prossimo-a-cagliari-il-servizio-di-nettezza-urbana-potrebbe-essere-reso-in-misura-parziale"},"modified":"2013-11-13T17:20:43","modified_gmt":"2013-11-13T16:20:43","slug":"per-lo-sciopero-generale-nazionale-di-venerdi-prossimo-a-cagliari-il-servizio-di-nettezza-urbana-potrebbe-essere-reso-in-misura-parziale","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/13\/per-lo-sciopero-generale-nazionale-di-venerdi-prossimo-a-cagliari-il-servizio-di-nettezza-urbana-potrebbe-essere-reso-in-misura-parziale\/","title":{"rendered":"Per lo sciopero generale nazionale di venerd\u00ec prossimo a Cagliari il servizio di nettezza urbana potrebbe essere reso in misura parziale."},"content":{"rendered":"<p>In occasione dello sciopero generale nazionale di 4 ore del prossimo venerd\u00ec 15 novembre 2013 il servizio di nettezza urbana potrebbe essere reso in misura parziale.<\/p>\n<p>Saranno garantiti il servizio di raccolta e trasporto dei rifiuti delle scuole, ospedali, caserme, carceri ecc., il servizio di spazzamento, raccolta e lavaggio dei mercati civici sia fissi che mobili. Saranno altres\u00ec garantiti i servizi urgenti contingenti e\/o su segnalazione dell'autorit\u00e0 sanitaria o di pubblica sicurezza, compresa la raccolta di siringhe ed ogni altro caso che sia oggetto di ordinanza emessa dalle medesime autorit\u00e0 sanitarie e\/o di pubblica sicurezza.<\/p>\n<p>Sempre nella giornata di venerd\u00ec 15 novembre l'eventuale adesione allo sciopero nazionale da parte del personale del Comune di Cagliari potrebbe causare l'interruzione di diversi servizi al pubblico.<\/p>\n<p>Saranno anche in questo caso garantiti tutti i servizi essenziali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione dello sciopero generale nazionale di 4 ore del prossimo venerd\u00ec 15 novembre 2013 il servizio di nettezza urbana potrebbe essere reso in misura&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106911"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=106911"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106911\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=106911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=106911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=106911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}