{"id":106892,"date":"2013-11-14T17:20:43","date_gmt":"2013-11-14T16:20:43","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/14\/11\/2013\/arrestate-dai-carabinieri-due-persone-a-monserrato-per-i-reati-di-rapina-aggravata-in-concorso-e-porto-abusivo-di-armi-improprie"},"modified":"2013-11-14T17:20:43","modified_gmt":"2013-11-14T16:20:43","slug":"arrestate-dai-carabinieri-due-persone-a-monserrato-per-i-reati-di-rapina-aggravata-in-concorso-e-porto-abusivo-di-armi-improprie","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/14\/arrestate-dai-carabinieri-due-persone-a-monserrato-per-i-reati-di-rapina-aggravata-in-concorso-e-porto-abusivo-di-armi-improprie\/","title":{"rendered":"Arrestate dai carabinieri due persone a Monserrato per i reati di rapina aggravata in concorso e porto abusivo di armi improprie"},"content":{"rendered":"<p>Alle ore 19,30 del 13 novembre, una pattuglia della Stazione di Monserrato, mentre transitava nella via San Gottardo ha notato un\u2019autovettura di colore amaranto e nera con targa inglese, posizionata di traverso sopra lo sterrato della rotatoria, dove i militari sono stati fermati da Giacomo Caria, il quale ha affermato di&nbsp; aver subito il furto della sua autovettura, la stessa che si trovava di traverso sulla rotatoria.<\/p>\n<p>La presunta vittima del furto dell\u2019auto, ha raccontava di essere andato in&nbsp; un tabacchino nelle vicinanze, in compagnia di Andrea Schirru, suo amico, e qui aveva lasciato l\u2019auto in sosta con le chiavi inserite nel quadro ed all\u2019uscita non avrebbe pi\u00f9 trovato l\u2019autovettura. Per questo motivo, aveva fermato un automobilista per correre dietro alla sua autovettura che nell\u2019inseguimento era finita fuori strada con la conseguente fuga dei ladri.<\/p>\n<p>Nel frattempo per\u00f2 Gigliola Lupi, aveva denunciato alla centrale Operativa della Compagnia CC di Quartu Sant\u2019Elena,&nbsp; che presso la sua agenzia di assicurazioni, si erano presentati due individui vestiti di nero e completamente travisati, uno pi\u00f9 alto, sul metro e ottanta e uno pi\u00f9 basso sul metro e settantacinque che le hanno intimato di consegnare l\u2019incasso della giornata, brandendo un\u2019accetta ed un bastone. La donna, impaurita dai due, ha consegnato ai rapinatori la borsetta con tutti gli effetti personali e con circa Euro 400,00 in contanti. Quindi i due una volta impossessatisi della borsetta sarebbero scappati.<\/p>\n<p>A questo punto, ricollegati i fatti dagli&nbsp; uomini dell\u2019Arma in servizio, gli \u00e8 apparso chiaro di trovarsi di fronte all\u2019autovettura utilizzata per la rapina. Perci\u00f2 hanno trattenuto il Caria per avere maggiori chiarimenti. Subito dopo \u00e8 stato raggiunto da Schirru, che ha confermato la versione del primo.<BR>In seguito \u00e8 stato individuato il presunto automobilista che, contrariamente a quanto riferito dal Caria, ha affermato che,&nbsp; una Fiat Punto con targa inglese, avrebbe cozzato con la sua autovettura in sosta. Messosi all\u2019inseguimento si \u00e8 fermato quando la Fiat Punto \u00e8 andata a cozzare contro l\u2019aiuola sparti traffico. In quel momento gli occupanti del mezzo si sono dileguati, eccezion fatta per il&nbsp; Giacomo Caria che gli chiedeva ha chiesto di concordare una improbabile tesi:&nbsp; Giacomo Caria, quindi, in compagnia di Andrea Schirru, si erano fermati a comprare delle sigarette in un tabacchino lasciando l\u2019autovettura in sosta con le chiavi inserite e durante questa sosta un ladro era passato e aveva rubato l\u2019auto. In seguito Caria, visto passare l\u2019automobilista, gli aveva chiesto di inseguire la sua auto Fiat Punto con targa inglese che gli era stata appena rubata. Alla fine, i carabinieri non hanno creduto alla ricostruzione fatta dai due e si sono resi conto di trovarsi davanti ai due presunti autori della rapina compiuta poco prima nell\u2019agenzia di assicurazioni di Monserrato, perci\u00f2&nbsp; sono stati fermati, portati in caserma dove sono stati dichiarati in arresto e accompagnati e rinchiusi nel carcere cagliaritano di Buoncammino. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle ore 19,30 del 13 novembre, una pattuglia della Stazione di Monserrato, mentre transitava nella via San Gottardo ha notato un\u2019autovettura di colore amaranto e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106892"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=106892"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106892\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=106892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=106892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=106892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}