{"id":106845,"date":"2013-11-04T17:20:43","date_gmt":"2013-11-04T16:20:43","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/04\/11\/2013\/fed-cup-cossa-vicepresidente-consiglio-regionale-successo-delle-azzurre-e-il-successo-di-tutta-la-sardegna"},"modified":"2013-11-04T17:20:43","modified_gmt":"2013-11-04T16:20:43","slug":"fed-cup-cossa-vicepresidente-consiglio-regionale-successo-delle-azzurre-e-il-successo-di-tutta-la-sardegna","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/04\/fed-cup-cossa-vicepresidente-consiglio-regionale-successo-delle-azzurre-e-il-successo-di-tutta-la-sardegna\/","title":{"rendered":"Fed Cup, Cossa (Vicepresidente Consiglio regionale): &#8220;Successo delle azzurre \u00e8 il successo di tutta la Sardegna&#8221;"},"content":{"rendered":"<p>\u00abUn successo importante per l'Italia e per la Sardegna\u00bb. Commenta cos\u00ec il vice presidente del Consiglio regionale e coordinatore regionale dei Riformatori sardi, Michele Cossa, la conquista della Fed Cup da parte delle tenniste italiane.<\/p>\n<p>\"La vittoria delle azzurre - dice ancora Cossa -&nbsp; \u00e8 anche una vittoria della Sardegna e del suo capoluogo Cagliari, che hanno saputo accogliere con calore e colore la squadra e un evento importantissimo per lo sport internazionale. <\/p>\n<p>Una vetrina importate per l'Isola e per la sua capitale. Un'occasione sfruttata al meglio anche grazie alla grande sensibilit\u00e0 del presidente della Federtennis, Angelo Binaghi, che si \u00e8 dimostrato per l'ennesima volta un grande presidente e un grande organizzatore\".<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abUn successo importante per l&#8217;Italia e per la Sardegna\u00bb. Commenta cos\u00ec il vice presidente del Consiglio regionale e coordinatore regionale dei Riformatori sardi, Michele Cossa,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106845"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=106845"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106845\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=106845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=106845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=106845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}