{"id":106769,"date":"2013-11-13T17:20:43","date_gmt":"2013-11-13T16:20:43","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/13\/11\/2013\/identificato-e-denunciato-dai-carabinieri-di-budoni-in-stato-di-liberta-presunto-ladro-seriale-del-cagliaritano"},"modified":"2013-11-13T17:20:43","modified_gmt":"2013-11-13T16:20:43","slug":"identificato-e-denunciato-dai-carabinieri-di-budoni-in-stato-di-liberta-presunto-ladro-seriale-del-cagliaritano","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/13\/identificato-e-denunciato-dai-carabinieri-di-budoni-in-stato-di-liberta-presunto-ladro-seriale-del-cagliaritano\/","title":{"rendered":"Identificato e denunciato dai carabinieri di Budoni in stato di libert\u00e0 presunto ladro seriale del cagliaritano."},"content":{"rendered":"<p>Dopo lunghe ed impegnative indagini, i carabinieri della Stazione di Budoni hanno denunciato in stato di libert\u00e0 un cittadino originario del cagliaritano ma domiciliato a Budoni di 44 anni, ritenuto responsabile di numerosi furti avvenuti negli ultimi mesi in paese e nelle localit\u00e0 limitrofe. <BR>Da tempo i militari erano sulle tracce di un uomo che, con scaltrezza e spesso con il favore del buio, si introduceva in abitazioni e magazzini lasciati momentaneamente incustoditi e nel giro di pochi minuti li svaligiava. L\u2019autore dei furti, per\u00f2, \u00e8 stato infine identificato e, a seguito di una perquisizione all\u2019interno della sua abitazione, gli uomini dell\u2019Arma hanno rinvenuto il variegato provento delle sue scorribande: televisori, decoder, play station, stereo, modem, macchine da caff\u00e8, forni a microonde, aspirapolveri, trapani, cassette degli attrezzi da lavoro, binocoli, decespugliatori ed altro ancora. Quindi \u00e8 stato tutto sequestrato e parte della refurtiva \u00e8 gi\u00e0 stata riconsegnata ai legittimi proprietari ma sono ancora molti i materiali che devono essere restituiti.<\/p>\n<p>Coloro che hanno subito furti in abitazione negli ultimi mesi possono visionare gli oggetti trafugati presso la caserma cc di Budoni.<BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo lunghe ed impegnative indagini, i carabinieri della Stazione di Budoni hanno denunciato in stato di libert\u00e0 un cittadino originario del cagliaritano ma domiciliato a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106769"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=106769"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106769\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=106769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=106769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=106769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}