{"id":106737,"date":"2013-11-09T17:20:43","date_gmt":"2013-11-09T16:20:43","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/09\/11\/2013\/arrestato-dagli-agenti-della-mobile-cagliaritana-finto-poliziotto-furto"},"modified":"2013-11-09T17:20:43","modified_gmt":"2013-11-09T16:20:43","slug":"arrestato-dagli-agenti-della-mobile-cagliaritana-finto-poliziotto-furto","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/09\/arrestato-dagli-agenti-della-mobile-cagliaritana-finto-poliziotto-furto\/","title":{"rendered":"Arrestato dagli agenti della Mobile cagliaritana finto poliziotto furto"},"content":{"rendered":"<p>Nei giorni scorsi personale della Sezione Antirapina della Squadra Mobile della Questura di Cagliari, nell\u2019ambito dei servizi di polizia giudiziaria finalizzati alla prevenzione e alla repressione dei reati contro il patrimonio, \u00e8 stato pi\u00f9 volte chiamato nel quartiere Is Mirrionis per cercare di scoprire l\u2019individuo che, spacciandosi quale appartenente alle forze dell\u2019ordine, si era reso responsabile di numerosi furti ai danni di giovani studenti universitari, utilizzando come \u201cmodus operandi\u201d l\u2019esibizione di una placca identificativa e, dopo aver chiesto di visionare il portafoglio contenente i documenti personali, ne prelevava il danaro che vi erano dentro.<\/p>\n<p>Alle ore 10,45 circa di ieri, nel transitare in questa Via Carlo Baudi di Vesme, due Poliziotti della Squadra Mobile hanno notato in lontananza due persone colloquiare e, quindi hanno attirato subito la loro attenzione. <BR>Uno di questi alto 1,75 circa, di corporatura magra, che vestiva jeans e maglietta a maniche corte di colore marrone e righe orizzontali arancioni e portava sul capo capellino con visiera nero e occhiali da sole di colore nero, ha colpito&nbsp; i poliziotti, in modo particolare, perch\u00e9 riportava caratteristiche fisico somatiche molto simili al personaggio che, appunto, era stato protagonista di numerosi furti di denaro ai danni di giovani, creando negli stessi il convincimento di trovarsi davanti a un appartenente alla Polizia, mentre la seconda persona pi\u00f9 bassa, appariva uno studente. <BR>Gli agenti sono perci\u00f2 intervenuti ed hanno accertato poi che il portafoglio che il giovane pi\u00f9 alto teneva in mano era dell\u2019altro e che questi, prima del loro arrivo ha tentato inutilmente di rientrarne in possesso.<\/p>\n<p>Il giovane pi\u00f9 alto con il capellino nero ed occhiali, \u00e8 stato immediatamente bloccato ed identificati: si tratta di Salvatore Gervasi, mentre l\u2019altro giovane, uno studente universitario iscritto alla facolt\u00e0 di Lingue di Cagliari, ha riferito che era stato prima avvicinato dall\u2019altro il quale gli ha detto: \u201cmostrami i documenti, Polizia\u201d, mostrandogli in modo molto fugace, tanto da non permettergli di vedere chiaramente quanto rappresentato, un portadocumenti di colore nero, con in vista una placca metallica tipo distintivo, aggiungendo che era in atto un controllo di Polizia.<\/p>\n<p>La vittima, convinta di aver davanti un tutore dell\u2019ordine, ha estratto dalla tasca posteriore il suo portadocumenti dal quale ha preso la carta di identit\u00e0 e l\u2019ha data all\u2019uomo che l\u2019ha controllata. In quel frangente il sedicente \u201cpoliziotto\u201d, lo ha invitato a mostrare ogni oggetto in suo possesso quindi accorgendosi della presenza del portafoglio, si \u00e8 concentrato solo su quello e prendendolo nelle mani gli diceva che per questione di sicurezza, doveva fotocopiarlo, quindi, insieme, hanno percorso la strada per poi girare a sinistra in via Carlo Baudi di Vesme.<\/p>\n<p>Giunti davanti un negozio di mobili usati, Gervasi, \u00e8 entrato dicendo che all\u2019interno era presente un suo collega che avrebbe fotocopiato il contenuto del portafoglio. Il presunto agente \u00e8 rimasto, all\u2019interno dell\u2019esercizio commerciale qualche minuto, senza che nessuno lo avvicinasse o parlasse con lui. Quindi \u00e8 uscito fuori dicendo allo studente che non aveva trovato il suo collega e dopo aver camminato insieme per alcuni metri, il truffatore ha riconsegnato il portafoglio alla vittima che, aprendolo, ha per\u00f2 notato che erano sparite le banconote custodite all\u2019interno e precisamente la somma contante di \u20ac 35,00, composta da una banconota da \u20ac 20,00, una da \u20ac 10,00 ed una da \u20ac 5,00.<\/p>\n<p>Quest\u2019ultima scena era stata interamente osservata dal personale della Mobile che, resisi conto dell\u2019avvenuto furto dei soldi, sono intervenuti ponendo fine alla condotta criminosa. In seguito, Gervasi \u00e8 stato controllato e trovato in possesso di un portadocumenti di piccole dimensioni, contenente un distintivo di colore blu del Comune di Cagliari in uso alle guardie particolari giurate, la somma in contati di 35,00 euro (cosi come descritta dalla vittima), che lo stesso aveva nella tasca anteriore dei pantaloni, il capellino con visiera e gli occhiali neri. Il malfattore \u00e8 stato perci\u00f2 dichiarato in arresto e trattenuto in attesa del rito direttissimo previsto per oggi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei giorni scorsi personale della Sezione Antirapina della Squadra Mobile della Questura di Cagliari, nell\u2019ambito dei servizi di polizia giudiziaria finalizzati alla prevenzione e alla&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106737"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=106737"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106737\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=106737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=106737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=106737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}