{"id":106728,"date":"2013-11-09T17:20:43","date_gmt":"2013-11-09T16:20:43","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/09\/11\/2013\/super-tifone-sulle-filippine-per-la-croce-rossa-almeno-1200-i-morti"},"modified":"2013-11-09T17:20:43","modified_gmt":"2013-11-09T16:20:43","slug":"super-tifone-sulle-filippine-per-la-croce-rossa-almeno-1200-i-morti","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/09\/super-tifone-sulle-filippine-per-la-croce-rossa-almeno-1200-i-morti\/","title":{"rendered":"Super tifone sulle Filippine: per la Croce Rossa almeno 1200 i morti"},"content":{"rendered":"<p>Potrebbero essere oltre 1.200 i morti causati dal super tifone Haiyan (localmente si chiama Yolanda) nelle Filippine. Lo afferma la Croce Rossa, precisando di aver ricevuto rapporti sulle vittime a Tacloban e nella provincia di Samar.<\/p>\n<p>Gwendolyn Pang, segretario generale della Croce Rossa di Manila, riferisce che, \"le squadre\", dell'organizzazione, \"stimano di aver visto oltre 1.000 corpi galleggiare a Tacloban\", cui si aggiungono, \"circa 200 vittime a Samar. La verifica \u00e8 in corso\".<\/p>\n<p>\"Chiedo a tutti voi di unirvi a me nella preghiera per le vittime del tifone Haiyan-Yolanda, specialmente quelli nelle amate isole delle Filippine\". Lo scrive papa Francesco in un messaggio in inglese diffuso su Twitter.<BR>Il Papa, informa la Radio Vaticana, \u00e8 stato messo al corrente della drammatica situazione che sta vivendo il Paese ed esprime la sua \"vicinanza\" alla popolazione, assicurando la sua preghiera per le vittime. <\/p>\n<p>Il numero delle vittime del tifone Hayan nelle Filippine \"probabilmente aumenter\u00e0\". Lo ha dichiarato un comandante dell'esercito del Paese, generale Roy Deveraturda. Deveraturda ha spiegato di prevedere un aggravamento del bilancio dopo avere visto le fotografie della enorme devastazione causata dal tifone, che dopo aver colpito le Filippine si dirige verso il Vietnam.<\/p>\n<p>Dopo aver seminato morte e distruzione nell'arcipelago delle Filippine, il tifone Haiyan sta rapidamente arrivando sulle coste della Cina meridionale. Secondo i meteorologi cinesi, il tifone dovrebbe arrivare in nottata la provincia insulare di Hainan, per diventare il trentesimo e pi\u00f9 forte tifone dell'anno ad abbattersi sulle coste cinesi. Gi\u00e0 stamattina, ad una velocit\u00e0 di 35 chilometri l'ora, il tifone \u00e8 arrivato nelle acque del Mar Cinese Meridionale. Le autorit\u00e0 hanno richiamato in porto tutte le barche di pescatori, innalzando l'allarme per le onde da giallo ad arancione, il secondo livello di forza di un tifone subito dietro al livello rosso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Potrebbero essere oltre 1.200 i morti causati dal super tifone Haiyan (localmente si chiama Yolanda) nelle Filippine. Lo afferma la Croce Rossa, precisando di aver&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106728"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=106728"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106728\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=106728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=106728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=106728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}