{"id":106710,"date":"2013-11-11T17:20:43","date_gmt":"2013-11-11T16:20:43","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/11\/11\/2013\/industria---energia-liori-per-rilanciare-leconomia-bisogna-rendere-competitiva-la-sardegna"},"modified":"2013-11-11T17:20:43","modified_gmt":"2013-11-11T16:20:43","slug":"industria-energia-liori-per-rilanciare-leconomia-bisogna-rendere-competitiva-la-sardegna","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/11\/11\/industria-energia-liori-per-rilanciare-leconomia-bisogna-rendere-competitiva-la-sardegna\/","title":{"rendered":"Industria &#8211; Energia, Liori: Per rilanciare l&#8217;economia bisogna rendere competitiva la Sardegna"},"content":{"rendered":"<p>\"Un'azienda che testimonia le reali possibilit\u00e0 di riconversione economica in questo territorio\". Lo ha detto l'assessore dell'Industria, Antonello Liori, durante la visita allo stabilimento Cermed di Guspini. L'azienda, in una recente riunione tecnica sui costi dell'energia per l'attivit\u00e0 industriale, aveva invitato l'Assessore a visitare le strutture della Ceramica Mediterranea.<\/p>\n<p>\"Ho trovato uno stabilimento tecnologicamente avanzato, che utilizza materie prime sarde e dimostra anche un\u2019importante attenzione per i risvolti ambientali della propria attivit\u00e0. Si tratta di una realt\u00e0 produttiva importante, che in un territorio in grave crisi consente l\u2019occupazione di circa 100 lavoratori. Ho preso ulteriore coscienza di quanto sia indispensabile affrontare con decisione il problema dell\u2019approvvigionamento e dei costi dell\u2019energia, con l\u2019obiettivo di rendere competitiva la Sardegna per il rilancio delle attivit\u00e0 produttive\u201d, ha aggiunto Liori. Com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Un&#8217;azienda che testimonia le reali possibilit\u00e0 di riconversione economica in questo territorio&#8221;. Lo ha detto l&#8217;assessore dell&#8217;Industria, Antonello Liori, durante la visita allo stabilimento Cermed&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106710"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=106710"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/106710\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=106710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=106710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=106710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}