{"id":105355,"date":"2013-08-02T17:20:42","date_gmt":"2013-08-02T16:20:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/02\/08\/2013\/aperte-le-iscrizioni-per-nonno-vigile"},"modified":"2013-08-02T17:20:42","modified_gmt":"2013-08-02T16:20:42","slug":"aperte-le-iscrizioni-per-nonno-vigile","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/08\/02\/aperte-le-iscrizioni-per-nonno-vigile\/","title":{"rendered":"Aperte le iscrizioni per Nonno Vigile\u201d"},"content":{"rendered":"<p>Sono aperte le iscrizioni, rivolte a tutti i volontari anziani interessati, a partecipare al servizio di vigilanza e sicurezza denominato \u201cNonno Vigile\u201d presso le scuole elementari e medie statali di Cagliari, per l'anno scolastico 2013 \u2013 2014.<\/p>\n<p>Tra i requisiti l'aver compiuto 60 anni d'et\u00e0 (55 per le donne) e non aver superato il 72\u00b0.<\/p>\n<p>Essere muniti di idonea certificazione medica, non anteriore a tre mesi, rilasciata dal medico di base, attestante lo stato di buona salute e l'idoneit\u00e0 psico-fisica al servizio e all'attivit\u00e0 da svolgere.<\/p>\n<p>Essere pensionati o inoccupati, godere dei diritti civili e politici.<BR>Non aver riportato condanne penali e non avere carichi pendenti.<BR>Essere idonei a svolgere l'attivit\u00e0 anche sotto il profilo della seriet\u00e0 e responsabilit\u00e0.<\/p>\n<p>Essere muniti di idonea certificazione ISEE riferita ai redditi 2012.<BR>Le richieste dovranno essere presentate presso la sede della Societ\u00e0 degli Operai di Mutuo Soccorso in via XX Settembre, bo a Cagliari Tel. 070.656821 entro il 5 settembre 2013.<\/p>\n<p>Verr\u00e0 stabilita un'apposita graduatoria dalla quale sar\u00e0 attinto il personale necessario.<BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono aperte le iscrizioni, rivolte a tutti i volontari anziani interessati, a partecipare al servizio di vigilanza e sicurezza denominato \u201cNonno Vigile\u201d presso le scuole&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105355"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=105355"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105355\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=105355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=105355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=105355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}