{"id":105271,"date":"2013-07-17T17:20:42","date_gmt":"2013-07-17T16:20:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/17\/07\/2013\/consorzio-ogliastra---liori-servono-soluzioni-per-grave-situazione-finanziaria"},"modified":"2013-07-17T17:20:42","modified_gmt":"2013-07-17T16:20:42","slug":"consorzio-ogliastra-liori-servono-soluzioni-per-grave-situazione-finanziaria","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/07\/17\/consorzio-ogliastra-liori-servono-soluzioni-per-grave-situazione-finanziaria\/","title":{"rendered":"Consorzio Ogliastra &#8211; Liori: &#8216;Servono soluzioni per grave situazione finanziaria&#8217;"},"content":{"rendered":"<p> \"Fermo restando la necessit\u00e0 di accelerare in Consiglio regionale l'iter legislativo della riforma dei Consorzi, la grave situazione finanziaria del Consorzio industriale Ogliastra va affrontata con decisione e tempestivit\u00e0. Lo ha detto l'assessore dell'Industria, Antonello Liori, durante l'incontro di questa mattina con il responsabile amministrativo del Consorzio, Michele Moi, al quale ha partecipato anche il consigliere regionale ogliastrino, Angelo Stochino.<\/p>\n<p>\"Durante la prossima settimana, - ha aggiunto Liori - incontrer\u00f2 i vertici di Abbanoa e dell'Assessorato regionale dei Trasporti. Infatti, per trovare una soluzione al problema occorre affrontare soprattutto le questioni del depuratore, con il suo trasferimento ad Abbanoa, e dell'aeroporto di Tortol\u00ec. Due voci che condizionano fortemente il bilancio del Consorzio. Dobbiamo individuare una soluzione anche per restituire una dose di ottimismo ai tanti lavoratori senza stipendio da alcuni mesi.\"<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Fermo restando la necessit\u00e0 di accelerare in Consiglio regionale l&#8217;iter legislativo della riforma dei Consorzi, la grave situazione finanziaria del Consorzio industriale Ogliastra va affrontata&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105271"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=105271"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105271\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=105271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=105271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=105271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}