{"id":105229,"date":"2013-07-16T17:20:42","date_gmt":"2013-07-16T16:20:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/16\/07\/2013\/kyenge-calderoli-chiede-scusa-ma-non-si-dimette-e-letta-afferma-che-maroni-e-correo"},"modified":"2013-07-16T17:20:42","modified_gmt":"2013-07-16T16:20:42","slug":"kyenge-calderoli-chiede-scusa-ma-non-si-dimette-e-letta-afferma-che-maroni-e-correo","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/07\/16\/kyenge-calderoli-chiede-scusa-ma-non-si-dimette-e-letta-afferma-che-maroni-e-correo\/","title":{"rendered":"Kyenge: Calderoli chiede scusa ma non si dimette e letta afferma che Maroni \u00e8 correo"},"content":{"rendered":"<p>Nei confronti del ministro Kyenge \"ho usato, preso dalla foga di un comizio, una frase esecrabile, che non voleva avere significato razziale o razzista, e di cui mi scuso con lei, presidente, e con il Senato, per aver con essa reso nocumento al Senato\". Lo ha detto il vice presidente del Senato Roberto Calderoli, prendendo la parola in aula a palazzo Madama.<br \/>Calderoli si \u00e8 detto \"grato al ministro per aver accettato le mie scuse\" e ha specificato che se ieri non ha partecipato alla seduta \u00e8 solo perch\u00e9 era impegnato a Milano nella segreteria della Lega. <\/p>\n<p>Calderoli ha ammesso di aver commesso l'errore di \"spostare il confronto dal piano politico a quello personale\" e ha dato la parola d'onore che non accadr\u00e0 pi\u00f9.<\/p>\n<p>Quanto alle dimissioni, Calderoli ha ricordato di aver dimostrato coraggio nel darle in passato, ma ha specificato che nel dibattito di ieri non \u00e8 emersa una maggioranza amplissima in favore delle stesse, nel qual caso non avrebbe avuto difficolt\u00e0 a rassegnarle, e perci\u00f2 non lascer\u00e0 l'incarico di vice presidente. A Kyenge, comunque, \"come suggerito ieri dal senatore Compagna, invier\u00f2 un mazzo di rose\" ha assicurato Calderoli.<\/p>\n<p>''La questione per me \u00e8 chiusa e lo dico da ieri''. Cos\u00ec il segretario federale della Lega Nord, Roberto Maroni, risponde ai giornalisti in merito all'ipotesi di possibili dimissioni da parte del vicepresidente del Senato, Roberto Calderoli, dopo i suoi attacchi al ministro dell'Integrazione, Cecile Kyenge.<\/p>\n<p>\"Altro che tutto rientrato! La scivolata \u00e8 solo quella di un leader che non riesce a far dimettere Calderoli da vicepresidente del Senato\". E' questa la reazione che trapela da P. Chigi a Maroni. \"Purtroppo \u00e8 una carica che non \u00e8 oggetto di voce di sfiducia, ma cos\u00ec facendo Maroni \u00e8 correo dell'insulto al ministro Kyenge\", concludono.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei confronti del ministro Kyenge &#8220;ho usato, preso dalla foga di un comizio, una frase esecrabile, che non voleva avere significato razziale o razzista, e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105229"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=105229"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105229\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=105229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=105229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=105229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}