{"id":105181,"date":"2013-07-17T17:20:42","date_gmt":"2013-07-17T16:20:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/17\/07\/2013\/concorso-nazionale-per-fotografi-e-pittori-dilettanti--immagini-e-quadri-per-ritrarre-gli-artigiani-del-proprio-quartiere"},"modified":"2013-07-17T17:20:42","modified_gmt":"2013-07-17T16:20:42","slug":"concorso-nazionale-per-fotografi-e-pittori-dilettanti-immagini-e-quadri-per-ritrarre-gli-artigiani-del-proprio-quartiere","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/07\/17\/concorso-nazionale-per-fotografi-e-pittori-dilettanti-immagini-e-quadri-per-ritrarre-gli-artigiani-del-proprio-quartiere\/","title":{"rendered":"Concorso Nazionale per fotografi e pittori dilettanti \u2013 Immagini e quadri per ritrarre gli artigiani del proprio quartiere"},"content":{"rendered":"<p>Macchina fotografica o pennelli, scheda digitale o colori, treppiede o tavolozza: l\u2019importante \u00e8 ritrarre gli artigiani e i loro mestieri, e partecipare cos\u00ec al concorso nazionale di Confartigianato che assegner\u00e0 interessanti premi d\u2019acquisto del valore di 1.000, 600 e 300 euro.<\/p>\n<p>L\u2019ANAP Confartigianato, infatti, ha bandito un concorso per fotografi e pittori non professionisti che, con le loro opere, saranno capaci di raffigurare al meglio gli artigiani e la loro manualit\u00e0 all\u2019interno dei loro quartieri.<\/p>\n<p>\u201cQuesta \u00e8 la terza edizione del concorso e ci auguriamo che questa volta uno dei premi possa arrivare in Sardegna \u2013 afferma Paola Montis, Presidente dell\u2019ANAP Sardegna (Associazione Nazionale Anziani e Pensionati) di Confartigianato \u2013 anche se l\u2019importante \u00e8 divertirsi e riuscire a cogliere l\u2019essenza dei maestri artigiani e della loro attivit\u00e0 quotidiana\u201d.<\/p>\n<p>\u201cE\u2019 una bella occasione soprattutto per andare a \u201ccaccia\u201d di immagini per riscoprire quei volti, quell\u2019arte e quella manualit\u00e0 che magari vediamo tutti i giorni ma che non riusciamo a fissare \u2013 continua la Montis \u2013 ed \u00e8 il modo per partecipare a un \u201cgioco\u201d molto divertente\u201d.<\/p>\n<p>\u201cPossiamo augurare un in bocca al lupo a tutti i partecipanti \u2013 conclude la Presidente dell\u2019Anap Sardegna \u2013dicendo \u201cFate dell\u2019arte la vostra arte\u201d\u201d.<\/p>\n<p>Ritratti o fotografie, dovranno essere originali, consegnati entro il 15 agosto e verranno esposte per una settimana in Sicilia durante lo svolgimento della Festa Nazionale del Socio ANAP e valutati da una giuria popolare.<\/p>\n<p>L\u2019iniziativa, i cui regolamenti e schede di partecipazione sono reperibili presso il sito <a href=\"http:\/\/www.confartigianatosardegna.it\">www.confartigianatosardegna.it<\/a>, \u00e8 rivolta ai soci di Confartigianato Imprese Sardegna, Anap e Ancos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Macchina fotografica o pennelli, scheda digitale o colori, treppiede o tavolozza: l\u2019importante \u00e8 ritrarre gli artigiani e i loro mestieri, e partecipare cos\u00ec al concorso&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105181"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=105181"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105181\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=105181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=105181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=105181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}