{"id":105135,"date":"2013-07-17T17:20:42","date_gmt":"2013-07-17T16:20:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/17\/07\/2013\/istat-su-crisi-aumentano-i-poveri-record-dal-2005"},"modified":"2013-07-17T17:20:42","modified_gmt":"2013-07-17T16:20:42","slug":"istat-su-crisi-aumentano-i-poveri-record-dal-2005","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/07\/17\/istat-su-crisi-aumentano-i-poveri-record-dal-2005\/","title":{"rendered":"Istat su crisi. Aumentano i poveri, record dal 2005"},"content":{"rendered":"<p>Cresce il numero di persone e di famiglie povere in Italia. Nel 2012 gli individui in povert\u00e0 relativa sono risultati 9 milioni e 563mila pari al 15,8% della popolazione (13,6% nel 2011), 4 milioni e 814mila dei quali in povert\u00e0 assoluta (i pi\u00f9 poveri tra i poveri misurati sulla base di un paniere e servizi essenziali) pari all'8% della popolazione (5,7% nel 2011). E' quanto rileva l'Istat nel Rapporto sulla povert\u00e0 in Italia. <\/p>\n<p>Il 12,7% delle famiglie \u00e8 relativamente povero per un totale di 3 milioni e 232mila, il 6,8% delle quali lo \u00e8 in termini assoluti pari a un milione e 725mila. Tra il 2011 e il 2012 \u00e8 aumentata sia l'incidenza di povert\u00e0 relativa (dall'11,1% al 12,7%) che quella di povert\u00e0 assoluta (dal 5,2% al 6,8%), in tutte e tre le ripartizioni geografiche.<\/p>\n<p>Per quanto riguarda la povert\u00e0 assoluta, sottolinea l'Istat, si tratta del livello pi\u00f9 alto mai registrato dal 2005, inizio della misurazione della povert\u00e0 assoluta.<\/p>\n<p>La crisi economica, spiega l'istituto di statistica, ha giocato un ruolo \"fondamentale\" nel peggioramento delle dinamiche della povert\u00e0. La soglia di povert\u00e0 relativa per una famiglia di due componenti \u00e8 pari a 990,88 euro (circa 20 euro in meno di quella dell'anno precedente, -2%). La povert\u00e0 assoluta viene misurata sulla base di una lista di beni e servizi, varata da una commissione di studio nel 2005 insieme con l'Istat, per poter svolgere una vita dignitosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cresce il numero di persone e di famiglie povere in Italia. Nel 2012 gli individui in povert\u00e0 relativa sono risultati 9 milioni e 563mila pari&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105135"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=105135"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105135\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=105135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=105135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=105135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}