{"id":105074,"date":"2013-07-22T17:20:42","date_gmt":"2013-07-22T16:20:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/22\/07\/2013\/dichiarava-di-essere-il-comandante-della-compagnia-carabinieri-e-della-guardia-di-finanza-per-farsi-accreditare-del-denaro-denunciato-dai-militari-della-stazione-cc-di-budoni-truffatore-seria"},"modified":"2013-07-22T17:20:42","modified_gmt":"2013-07-22T16:20:42","slug":"dichiarava-di-essere-il-comandante-della-compagnia-carabinieri-e-della-guardia-di-finanza-per-farsi-accreditare-del-denaro-denunciato-dai-militari-della-stazione-cc-di-budoni-truffatore-seriale","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/07\/22\/dichiarava-di-essere-il-comandante-della-compagnia-carabinieri-e-della-guardia-di-finanza-per-farsi-accreditare-del-denaro-denunciato-dai-militari-della-stazione-cc-di-budoni-truffatore-seriale\/","title":{"rendered":"Dichiarava di essere il comandante della compagnia carabinieri e della Guardia di Finanza per farsi accreditare del denaro, denunciato dai militari della Stazione cc di Budoni truffatore seriale."},"content":{"rendered":"<p>Da diversi giorni i carabinieri di Budoni erano sulle tracce di un uomo, identificato poi in V.G., casertano di 32 anni, che, spacciandosi alle volte per il comandante della Stazione cc e della Compagnia dei Carabinieri ed alle volte per quello della Guardia di finanza, tentava di farsi accreditare del denaro su due carte prepagate Eni (di cui una intestata alla sua complice, F.C., 71enne anch\u2019essa di Caserta).<\/p>\n<p>In ben quattro occasioni, in particolare, il truffatore \u00e8 riuscito, grazie ad artifizi e raggiri, a convincere telefonicamente il titolare di un\u2019area di servizio, sempre presentandosi nel modo sopra indicato, ad accreditare 250 euro, per un totale di 1000 euro, sulle carte di credito segnalate.<\/p>\n<p>Dopo complesse ed articolate indagini, gli investigatori dell\u2019Arma della Stazione di Budoni sono riusciti ad identificare i truffatori: pertanto V.G. e F.C., entrambi pregiudicati e nullafacenti, sono quindi stati denunciati e dovranno rispondere all\u2019autorit\u00e0 giudiziaria di truffa (entrambi) e sostituzione di persona (il V.G.).<BR><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da diversi giorni i carabinieri di Budoni erano sulle tracce di un uomo, identificato poi in V.G., casertano di 32 anni, che, spacciandosi alle volte&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105074"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=105074"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105074\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=105074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=105074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=105074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}