{"id":105058,"date":"2013-07-19T17:20:42","date_gmt":"2013-07-19T16:20:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/19\/07\/2013\/lunedi-prossimo-interventi-di-disinfestazione-contro-le-zecche-in-varie-vie-della-citta"},"modified":"2013-07-19T17:20:42","modified_gmt":"2013-07-19T16:20:42","slug":"lunedi-prossimo-interventi-di-disinfestazione-contro-le-zecche-in-varie-vie-della-citta","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/07\/19\/lunedi-prossimo-interventi-di-disinfestazione-contro-le-zecche-in-varie-vie-della-citta\/","title":{"rendered":"Luned\u00ec prossimo interventi di disinfestazione contro le zecche in varie vie della citt\u00e0"},"content":{"rendered":"<p>Il prossimo<span class=\"apple-converted-space\"><span style=\"color: black;\">&nbsp;<\/span><\/span><b>luned\u00ec 22 luglio a partire dalle8,30<\/b>, gli operatori del Servizio provinciale antinsetti effettueranno unintervento di disinfestazione contro le zecche presso la Via Barracca Manna,dall'incrocio di Via Allinari fino all'incrocio con Via Della Menta, incorrispondenza della sede stradale, marciapiedi e muri perimetrali esterni.<\/p>\n<p>Durante la disinfestazione gli abitanti delle casecircostanti dovranno mettere al sicuro, all\u2019interno degli edifici, biancheria,giocattoli, animali domestici e tutto quanto pu\u00f2 essere usato a scopoalimentare. Dovranno tenere chiusi gli infissi esterni (anche dopo laconclusione della disinfestazione, per almeno un\u2019ora). Inoltre dovrannoastenersi per almeno 30 giorni dal consumare ortaggi e frutta eventualmentecoltivati nei terreni limitrofi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il prossimo&nbsp;luned\u00ec 22 luglio a partire dalle8,30, gli operatori del Servizio provinciale antinsetti effettueranno unintervento di disinfestazione contro le zecche presso la Via Barracca Manna,dall&#8217;incrocio&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105058"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=105058"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/105058\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=105058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=105058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=105058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}