{"id":104881,"date":"2013-07-13T17:20:42","date_gmt":"2013-07-13T16:20:42","guid":{"rendered":"http:\/\/www.cronacaonline.it\/public\/content\/index.php\/13\/07\/2013\/grazia-a-berlusconi-la-presidenza-della-repubblica-risponde-analfabetismo-istituzionale"},"modified":"2013-07-13T17:20:42","modified_gmt":"2013-07-13T16:20:42","slug":"grazia-a-berlusconi-la-presidenza-della-repubblica-risponde-analfabetismo-istituzionale","status":"publish","type":"post","link":"https:\/\/www.cronacaonline.it\/index.php\/2013\/07\/13\/grazia-a-berlusconi-la-presidenza-della-repubblica-risponde-analfabetismo-istituzionale\/","title":{"rendered":"Grazia a Berlusconi, la presidenza della Repubblica risponde: analfabetismo istituzionale."},"content":{"rendered":"<p>\"Libero ribadisce la propria linea: fonti vicine al Quirinale, altrettanto credibili, confermano che l'ipotesi grazia&nbsp;\u00e8 sulla scrivania del Colle\". E' questa la risposta del quotidiano Libero a fonti del Quirinale secondo cui l'ipotesi di un'eventuale grazia a Silvio Berlusconi, ventilata oggi dal quotidiano diretto da Maurizio Belpietro, sarebbe \"un segno di analfabetismo e sguaiatezza istituzionale\".<\/p>\n<p>\"Si smentisce nel modo pi\u00f9 assoluto che ci siano sulla scrivania del presidente pratiche immaginarie come quella descritta\". Lo affermano fonti del Quirinale in riferimento a fonti di stampa che insistono sull'ipotesi di una pratica sulla grazia giacente sulla scrivania del capo dello Stato.<br \/>\"Analfabetismo e sguaiatezza istituzionale\". Cosi' ambienti del Quirinale, interpellati, commentano l'ipotesi della concessione di una eventuale grazia a Silvio Berlusconi, ventilata oggi dal quotidiano, nel caso venisse condannato definitivamente nel processo Mediaset.<\/p>\n<p>Queste speculazioni, chiariscono le stesse fonti, rappresentano \"il segno di una assoluta irresponsabilita' politica che puo' soltanto avvelenare il clima della vita pubblica\". Parlare di grazia, proseguono le fonti del Quirinale, \"\u00e8 una delle abituali provocazioni di certi giornali che per la loro sguaiatezza e rozzezza dal punto di vista istituzionale non meritano alcuna attenzione ne' tanto meno alcun commento\".<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Libero ribadisce la propria linea: fonti vicine al Quirinale, altrettanto credibili, confermano che l&#8217;ipotesi grazia&nbsp;\u00e8 sulla scrivania del Colle&#8221;. E&#8217; questa la risposta del quotidiano&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[49],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/104881"}],"collection":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/comments?post=104881"}],"version-history":[{"count":0,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/posts\/104881\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/media?parent=104881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/categories?post=104881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronacaonline.it\/index.php\/wp-json\/wp\/v2\/tags?post=104881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}